{"id":94269,"date":"2022-05-14T21:46:23","date_gmt":"2022-05-15T00:46:23","guid":{"rendered":"https:\/\/www.cordobatimes.com\/showup\/?p=94269"},"modified":"2022-05-14T21:46:23","modified_gmt":"2022-05-15T00:46:23","slug":"britney-spears-perdio-al-bebe-que-estaba-esperando-con-sam-asghari","status":"publish","type":"post","link":"https:\/\/www.cordobatimes.com\/showup\/famosos\/2022\/05\/14\/britney-spears-perdio-al-bebe-que-estaba-esperando-con-sam-asghari\/","title":{"rendered":"Britney Spears perdi\u00f3 al beb\u00e9 que estaba esperando con Sam Asghari"},"content":{"rendered":"<h3><strong>El pasado 11 de abril, la \u201cPrincesa del pop\u201d hab\u00eda compartido que estaba embarazada, la pareja explic\u00f3 a sus fans que probablemente debieron esperar m\u00e1s tiempo para hacerlo p\u00fablico.<\/strong><\/h3>\n<p>A trav\u00e9s de su cuenta de Instagram, la cantante\u00a0Britney Spears\u00a0comparti\u00f3 un anuncio lamentable, pues\u00a0perdi\u00f3 al beb\u00e9 que estaba esperando\u00a0desde el pasado 11 de abril junto a su prometido\u00a0Sam Asghari.<\/p>\n<p>\u201cCon una profunda tristeza tenemos que anunciar que perdimos a nuestro beb\u00e9 en una etapa muy prematura del embarazo. Esto es devastador para cualquier padre\u201d, se pudo leer en el comunicado. En el breve texto, Sam y Britney tambi\u00e9n explicaron que tal vez debieron esperar m\u00e1s tiempo antes de anunciar el embarazo.<\/p>\n<p>\u201cProbablemente\u00a0debimos esperar m\u00e1s tiempo antes de anunciarlo, hasta estar m\u00e1s seguros del embarazo, pero est\u00e1bamos muy emocionados y\u00a0quer\u00edamos compartir la buena noticia\u201d, escribieron.<\/p>\n<p>Los futuros esposos tambi\u00e9n pidieron a la opini\u00f3n p\u00fablica que respete su privacidad y dejaron en claro que se sienten agradecidos por el apoyo de sus fans. De igual forma,\u00a0compartieron que volver\u00e1n a intentar concebir un beb\u00e9:<\/p>\n<p>\u201cEl amor del uno por el otro es nuestra mayor fuerza en esta situaci\u00f3n,\u00a0seguiremos tratando de expandir nuestra bell\u00edsima familia, estamos muy agradecidos por todo su apoyo. Amablemente\u00a0les pedimos privacidad durante estos momentos tan dif\u00edciles\u201d, expresaron.<\/p>\n<p><img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-94271 size-full\" src=\"https:\/\/www.cordobatimes.com\/showup\/wp-content\/uploads\/2022\/05\/Pantallazo-14-05-2022-21.34.02.jpg\" alt=\"\" width=\"535\" height=\"711\" srcset=\"https:\/\/www.cordobatimes.com\/showup\/wp-content\/uploads\/2022\/05\/Pantallazo-14-05-2022-21.34.02.jpg 535w, https:\/\/www.cordobatimes.com\/showup\/wp-content\/uploads\/2022\/05\/Pantallazo-14-05-2022-21.34.02-316x420.jpg 316w\" sizes=\"auto, (max-width: 535px) 100vw, 535px\" \/><\/p>\n<p>Por su parte,\u00a0Sam Asghari\u00a0le dirigi\u00f3 el siguiente mensaje a la cantante:\u00a0\u201cTendremos un beb\u00e9 milagro pronto\u201d;\u00a0ya que en la descripci\u00f3n de la foto, la int\u00e9rprete de\u00a0Toxic\u00a0escribi\u00f3: \u201cAgradecemos lo que tenemos en el proceso de expandir nuestra hermosa familia.\u00a0Gracias por su apoyo\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado 11 de abril, la \u201cPrincesa del pop\u201d hab\u00eda compartido que estaba embarazada, la pareja explic\u00f3 a sus fans que probablemente debieron esperar m\u00e1s tiempo para hacerlo p\u00fablico. A trav\u00e9s de su cuenta de Instagram, la cantante\u00a0Britney Spears\u00a0comparti\u00f3 un anuncio lamentable, pues\u00a0perdi\u00f3 al beb\u00e9 que estaba esperando\u00a0desde el pasado 11 de abril junto a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":94270,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[4],"tags":[35103,32894,35104],"class_list":{"0":"post-94269","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-famosos","8":"tag-britney-spears-perdio-su-embarazo","9":"tag-britney-spears-y-sam-asghari","10":"tag-embarazo-de-britney-spears"},"_links":{"self":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts\/94269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/comments?post=94269"}],"version-history":[{"count":0,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts\/94269\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/media\/94270"}],"wp:attachment":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/media?parent=94269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/categories?post=94269"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/tags?post=94269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}