{"id":92985,"date":"2022-02-04T09:23:44","date_gmt":"2022-02-04T12:23:44","guid":{"rendered":"https:\/\/www.cordobatimes.com\/showup\/?p=92985"},"modified":"2022-02-04T09:23:44","modified_gmt":"2022-02-04T12:23:44","slug":"las-lagrimas-de-flor-pena-al-escuchar-el-testimonio-de-fernan-miras","status":"publish","type":"post","link":"https:\/\/www.cordobatimes.com\/showup\/tv\/2022\/02\/04\/las-lagrimas-de-flor-pena-al-escuchar-el-testimonio-de-fernan-miras\/","title":{"rendered":"Las l\u00e1grimas de Flor Pe\u00f1a al escuchar el  testimonio de Fern\u00e1n Mir\u00e1s"},"content":{"rendered":"<h3><strong>En octubre, el actor hab\u00eda sufrido un aneurisma cerebral, motivo por el cual estuvo internado en terapia intensiva.<\/strong><\/h3>\n<p>Fern\u00e1n Mir\u00e1s\u00a0es sin dudas uno de los actores argentinos m\u00e1s queridos por el p\u00fablico y es por eso que en octubre, su salud preocup\u00f3 a todos cuando trascendi\u00f3 que\u00a0hab\u00eda tenido un aneurisma cerebral,\u00a0motivo por el cual debieron colocarle un stent. Por ese entonces, se encontraba protagonizando\u00a0ART, junto a Mike Amigorena y Pablo Echarri, obra dirigida por Germ\u00e1n Palacios y Ricardo Dar\u00edn\u00a0que debi\u00f3 suspender sus funciones.\u00a0\u201c\u00a1Gracias a todos!\u00a0Me han tirado tanta buena onda que moqueo.\u00a0No puedo usar el tel\u00e9fono, quer\u00eda agradecerles por tanto y por los chistes tambi\u00e9n.\u00a0Estoy muy bien, la saqu\u00e9 barata y la agarramos a tiempo\u201d, hab\u00eda escrito en su cuenta de\u00a0Twitter\u00a0mientras a\u00fan permanec\u00eda internado.<\/p>\n<p>Luego de\u00a0recibir el alta, d\u00edas atr\u00e1s, en una entrevista con\u00a0Germ\u00e1n Paoloski,\u00a0se hab\u00eda emocionado al recordar el dif\u00edcil momento\u00a0que vivi\u00f3 el a\u00f1o pasado. \u201cYo dej\u00e9 un par de mensajes despidi\u00e9ndome porque si me mor\u00eda, era peligrosa la operaci\u00f3n. Si hablo de eso lloro, pero le dej\u00e9 un mensaje a mis hijos fingiendo algo casual, pero dije \u2018de \u00faltima, que tengan un \u00faltimo mensaje\u2019\u201d.<\/p>\n<p>Y este martes, invitado a Flor de equipo, el programa que conduce Flor Pe\u00f1a en Telefe, rememor\u00f3 m\u00e1s detalles, lo que provoc\u00f3 las l\u00e1grimas de la anfitriona y de todo el panel. \u201cUna vez que le mand\u00e9 mensaje a mis hijos, le dije al m\u00e9dico que me opere porque me dol\u00eda mucho la cabeza. Y la zaf\u00e9\u201d, dijo el actor a punto de quebrar en llanto y provocando tambi\u00e9n la emoci\u00f3n en todos los presentes en el estudio. Incluso, en ese momento le tendi\u00f3 la mano en clara se\u00f1al de contenci\u00f3n.<\/p>\n<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/C467cXIoYGc\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En octubre, el actor hab\u00eda sufrido un aneurisma cerebral, motivo por el cual estuvo internado en terapia intensiva. Fern\u00e1n Mir\u00e1s\u00a0es sin dudas uno de los actores argentinos m\u00e1s queridos por el p\u00fablico y es por eso que en octubre, su salud preocup\u00f3 a todos cuando trascendi\u00f3 que\u00a0hab\u00eda tenido un aneurisma cerebral,\u00a0motivo por el cual debieron [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":92986,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[2],"tags":[34360,34359,34361],"class_list":{"0":"post-92985","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tv","8":"tag-fernan-miras-en-flor-de-equipo","9":"tag-flor-pena-y-fernan-miras","10":"tag-llanto-de-flor-pena"},"_links":{"self":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts\/92985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/comments?post=92985"}],"version-history":[{"count":0,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts\/92985\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/media\/92986"}],"wp:attachment":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/media?parent=92985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/categories?post=92985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/tags?post=92985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}