{"id":92052,"date":"2021-11-11T10:28:12","date_gmt":"2021-11-11T13:28:12","guid":{"rendered":"https:\/\/www.cordobatimes.com\/showup\/?p=92052"},"modified":"2021-11-11T10:28:12","modified_gmt":"2021-11-11T13:28:12","slug":"ganadores-de-los-premios-konex-de-platino-y-de-brillante-del-espectaculo-argentino-2011-2020","status":"publish","type":"post","link":"https:\/\/www.cordobatimes.com\/showup\/tv\/2021\/11\/11\/ganadores-de-los-premios-konex-de-platino-y-de-brillante-del-espectaculo-argentino-2011-2020\/","title":{"rendered":"Ganadores de los Premios Konex de Platino y de Brillante del espect\u00e1culo argentino 2011-2020"},"content":{"rendered":"<h3><strong>Maril\u00fa Marini fue distinguida con el m\u00e1ximo galard\u00f3n que otorga la Fundaci\u00f3n Konex.<\/strong><\/h3>\n<p>Luis Ovsejevich,\u00a0el presidente de la Fundaci\u00f3n Konex, y\u00a0Ricardo Dar\u00edn,\u00a0el presidente del Gran Jurado de los Premios Konex 2021 Espect\u00e1culos, anunciaron a las personalidades que ostentaron la trayectoria m\u00e1s significativa de la \u00faltima d\u00e9cada (2011-2020). Estas figuras recibir\u00e1n el\u00a0Konex de Platino.<\/p>\n<p>En este contexto, el Gran Jurado seleccion\u00f3 a\u00a0Maril\u00fa Marini\u00a0como la personalidad m\u00e1s destacada del Espect\u00e1culo Argentino para recibir el\u00a0Konex de Brillante, m\u00e1ximo galard\u00f3n que otorga la Fundaci\u00f3n Konex.<\/p>\n<p>Cabe recordar que en las anteriores entregas el Konex de Brillante fue para\u00a0Luisa Vehil y Alfredo Alc\u00f3n\u00a0en 1981, Mar\u00eda Rosa Gallo\u00a0en 1991,\u00a0Norma Aleandro\u00a0en 2001 y\u00a0Ricardo Dar\u00edn\u00a0en 2011. Asimismo, el Gran Jurado design\u00f3 a\u00a0Agust\u00edn Alezzo y Leonardo Favio\u00a0para el Konex de Honor, que se otorga a una figura de sobresaliente relieve fallecida en la \u00faltima d\u00e9cada.<\/p>\n<p><img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-92054\" src=\"https:\/\/www.cordobatimes.com\/showup\/wp-content\/uploads\/2021\/11\/Marilu-Marini.jpg\" alt=\"\" width=\"702\" height=\"386\" srcset=\"https:\/\/www.cordobatimes.com\/showup\/wp-content\/uploads\/2021\/11\/Marilu-Marini.jpg 702w, https:\/\/www.cordobatimes.com\/showup\/wp-content\/uploads\/2021\/11\/Marilu-Marini-696x383.jpg 696w\" sizes=\"auto, (max-width: 702px) 100vw, 702px\" \/><\/p>\n<p>A su vez, premi\u00f3 con menciones especiales a destacadas personalidades por su significativo aporte. En el rubro Trayectoria distinguieron a\u00a0H\u00e9ctor Alterio y Pepe Soriano. Tambi\u00e9n hay menciones especiales a destacadas instituciones y agrupaciones, como el\u00a0Grupo de Titiriteros del Teatro San Mart\u00edn, el Grupo La Cochera, el Grupo Piel de Lava y el Teatro Nacional Cervantes.<\/p>\n<p>Los Konex de Platino, el Konex de Brillante, los Konex de Honor y las menciones especiales se entregar\u00e1n en el Acto Culminatorio de los Premios Konex\u00a0el pr\u00f3ximo martes 7 de diciembre de 2021 en Ciudad Cultural Konex.<\/p>\n<p>Cabe destacar que el pasado 26 de octubre se entregaron los Diplomas al M\u00e9rito a las 100 figuras m\u00e1s destacadas del Espect\u00e1culo. En estos premios, las 20 disciplinas consideradas fueron: Actriz de Teatro, Actor de Teatro, Director\/a de Teatro, Actriz de Cine, Actor de Cine, Director\/a de Cine, Actriz de TV, Actor de TV, Director\/a de TV, Int\u00e9rprete Femenina de Musical, Int\u00e9rprete Masculino de Musical, Unipersonal, Infantil y Juvenil, Documental, Gui\u00f3n, Conductor\/a, Escenograf\u00eda, Vestuario, Iluminaci\u00f3n y Producci\u00f3n.<\/p>\n<p><img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-92055\" src=\"https:\/\/www.cordobatimes.com\/showup\/wp-content\/uploads\/2021\/11\/Ricardo-Darin-en-la-entrega-de-los-diplomas-de-los-Premios-Konex-649x420.jpg\" alt=\"\" width=\"649\" height=\"420\" srcset=\"https:\/\/www.cordobatimes.com\/showup\/wp-content\/uploads\/2021\/11\/Ricardo-Darin-en-la-entrega-de-los-diplomas-de-los-Premios-Konex-649x420.jpg 649w, https:\/\/www.cordobatimes.com\/showup\/wp-content\/uploads\/2021\/11\/Ricardo-Darin-en-la-entrega-de-los-diplomas-de-los-Premios-Konex-696x451.jpg 696w, https:\/\/www.cordobatimes.com\/showup\/wp-content\/uploads\/2021\/11\/Ricardo-Darin-en-la-entrega-de-los-diplomas-de-los-Premios-Konex.jpg 706w\" sizes=\"auto, (max-width: 649px) 100vw, 649px\" \/><\/p>\n<p>En esta edici\u00f3n, homenajearon a figuras del espect\u00e1culo fallecidas durante la d\u00e9cada 2011-2020 que fueron galardonadas con el Premio Konex en ediciones anteriores. Se trata de personajes inolvidables, como\u00a0China Zorrilla, Fernando \u201cPino\u201d Solanas, Antonio Carrizo, Eduardo \u201cTato\u201d Pavlovsky, Sergio Ren\u00e1n, Diana \u00c1lvarez, Marcos Mundstock, Daniel Rabinovich, Hugo Arana y Alejandro Urdapilleta.<\/p>\n<p>Cabe recordar que cada a\u00f1o, desde 1980, la Fundaci\u00f3n Konex premia a una actividad diferente de la cultura argentina. En 2021 es el turno del espect\u00e1culo y se premia a las figuras m\u00e1s destacadas de la \u00faltima d\u00e9cada en 20 disciplinas determinadas.<\/p>\n<h3><strong>A continuaci\u00f3n todos los ganadores:<\/strong><\/h3>\n<p>1. Actriz de Teatro<\/p>\n<p>Maril\u00fa Marini<\/p>\n<p>2. Actor de Teatro<\/p>\n<p>Mario Alarc\u00f3n<\/p>\n<p>3. Director\/a de Teatro<\/p>\n<p>Claudio Tolcachir<\/p>\n<p>4. Actriz de Cine<\/p>\n<p>Mercedes Mor\u00e1n<\/p>\n<p>5. Actor de Cine<\/p>\n<p>Leonardo Sbaraglia<\/p>\n<p>6. Director\/a de Cine<\/p>\n<p>Dami\u00e1n Szifron<\/p>\n<p>7. Actriz de TV<\/p>\n<p>Nancy Dupl\u00e1a<\/p>\n<p>Eleonora Wexler<\/p>\n<p>8. Actor de TV<\/p>\n<p>Luis Brandoni<\/p>\n<p>9. Director\/a de TV<\/p>\n<p>Luis Ortega<\/p>\n<p>Bruno Stagnaro<\/p>\n<p>10. Int\u00e9rprete Femenina de Musical<\/p>\n<p>Karina K<\/p>\n<p>Alejandra Radano<\/p>\n<p>11. Int\u00e9rprete Masculino de Musical<\/p>\n<p>Roberto Peloni<\/p>\n<p>12. Unipersonal<\/p>\n<p>Mauricio Dayub<\/p>\n<p>13. Infantil y Juvenil<\/p>\n<p>Ana Alvarado<\/p>\n<p>14. Documental<\/p>\n<p>Andr\u00e9s Di Tella<\/p>\n<p>15. Gui\u00f3n<\/p>\n<p>Santiago Mitre<\/p>\n<p>16. Conductor\/a<\/p>\n<p>Iv\u00e1n De Pineda<\/p>\n<p>17. Escenograf\u00eda<\/p>\n<p>Mercedes Alfons\u00edn<\/p>\n<p>18. Vestuario<\/p>\n<p>Renata Schussheim<\/p>\n<p>19. Iluminaci\u00f3n<\/p>\n<p>Eli Sirlin<\/p>\n<p>20. Producci\u00f3n<\/p>\n<p>Mat\u00edas Mosteir\u00edn<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Maril\u00fa Marini fue distinguida con el m\u00e1ximo galard\u00f3n que otorga la Fundaci\u00f3n Konex. Luis Ovsejevich,\u00a0el presidente de la Fundaci\u00f3n Konex, y\u00a0Ricardo Dar\u00edn,\u00a0el presidente del Gran Jurado de los Premios Konex 2021 Espect\u00e1culos, anunciaron a las personalidades que ostentaron la trayectoria m\u00e1s significativa de la \u00faltima d\u00e9cada (2011-2020). Estas figuras recibir\u00e1n el\u00a0Konex de Platino. En este [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":92053,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[2],"tags":[33738,33737],"class_list":{"0":"post-92052","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tv","8":"tag-ganadores-de-los-premios-konex","9":"tag-ganadores-de-los-premios-konex-de-platino-y-de-brillante"},"_links":{"self":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts\/92052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/comments?post=92052"}],"version-history":[{"count":0,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts\/92052\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/media\/92053"}],"wp:attachment":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/media?parent=92052"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/categories?post=92052"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/tags?post=92052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}