{"id":91808,"date":"2021-10-22T11:32:50","date_gmt":"2021-10-22T14:32:50","guid":{"rendered":"https:\/\/www.cordobatimes.com\/showup\/?p=91808"},"modified":"2021-10-22T11:32:50","modified_gmt":"2021-10-22T14:32:50","slug":"la-1-5-18-la-fuerte-escena-de-sexo-de-agustina-cherri-y-gonzalo-heredia","status":"publish","type":"post","link":"https:\/\/www.cordobatimes.com\/showup\/tv\/2021\/10\/22\/la-1-5-18-la-fuerte-escena-de-sexo-de-agustina-cherri-y-gonzalo-heredia\/","title":{"rendered":"La 1\/5-18: La fuerte escena de sexo de Agustina Cherri y Gonzalo Heredia"},"content":{"rendered":"<h3><strong>Los actores que interpretan a Bruno y Lola en la tira de Polka tuvieron su primer encuentro \u00edntimo en la pantalla chica.<\/strong><\/h3>\n<p>Hace casi un mes que desembarc\u00f3 en la pantalla de El Trece la novela\u00a0La 1\/5-18, y a estas alturas los fan\u00e1ticos de la tira de Polka conocen la historia de cada personaje y esperan con ansias los encuentros entre las parejas. Por eso la noche del jueves result\u00f3 especial:\u00a0Gonzalo Heredia, quien interpreta a Bruno, y Agustina Cherri, que se pone en la piel de Lola, protagonizaron una fuerte escena de sexo que dio que hablar en las redes sociales.\u00a0Aunque existen opiniones divididas sobre los tri\u00e1ngulos amorosos que se complejizan cada vez m\u00e1s, los admiradores de \u201c#BruLola\u201d manifestaron su emoci\u00f3n al ver\u00a0el rom\u00e1ntico momento que coron\u00f3 su incipiente romance.<\/p>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-91808-1\" width=\"640\" height=\"360\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/www.cordobatimes.com\/showup\/wp-content\/uploads\/2021\/10\/videoplayback.mp4?_=1\" \/><a href=\"https:\/\/www.cordobatimes.com\/showup\/wp-content\/uploads\/2021\/10\/videoplayback.mp4\">https:\/\/www.cordobatimes.com\/showup\/wp-content\/uploads\/2021\/10\/videoplayback.mp4<\/a><\/video><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Los actores que interpretan a Bruno y Lola en la tira de Polka tuvieron su primer encuentro \u00edntimo en la pantalla chica. Hace casi un mes que desembarc\u00f3 en la pantalla de El Trece la novela\u00a0La 1\/5-18, y a estas alturas los fan\u00e1ticos de la tira de Polka conocen la historia de cada personaje y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":91809,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[2],"tags":[33613,33614,33612],"class_list":{"0":"post-91808","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tv","8":"tag-agustina-cherri-y-gonzalo-heredia","9":"tag-bruno-y-lola-1-5-18","10":"tag-escena-de-sexo-de-agustina-cherri-y-gonzalo-heredia"},"_links":{"self":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts\/91808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/comments?post=91808"}],"version-history":[{"count":0,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts\/91808\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/media\/91809"}],"wp:attachment":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/media?parent=91808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/categories?post=91808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/tags?post=91808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}