{"id":91221,"date":"2021-09-17T11:48:25","date_gmt":"2021-09-17T14:48:25","guid":{"rendered":"https:\/\/www.cordobatimes.com\/showup\/?p=91221"},"modified":"2021-09-17T11:48:25","modified_gmt":"2021-09-17T14:48:25","slug":"la-ironica-frase-de-marcelo-tinelli-despues-de-la-carta-de-cristina-kirchner","status":"publish","type":"post","link":"https:\/\/www.cordobatimes.com\/showup\/tv\/2021\/09\/17\/la-ironica-frase-de-marcelo-tinelli-despues-de-la-carta-de-cristina-kirchner\/","title":{"rendered":"La ir\u00f3nica frase de Marcelo Tinelli despu\u00e9s de la carta de Cristina Kirchner"},"content":{"rendered":"<h3><strong>El conductor se hizo eco de la crisis interna que vive el oficialismo y critic\u00f3 al Gobierno<\/strong><\/h3>\n<p>Tras una serie de d\u00edas \u00e1lgidos en la pol\u00edtica interna del Gobierno, despu\u00e9s de la contundente derrota oficialista en las PASO de las elecciones legislativas, Cristina Kirchner rompi\u00f3 el silencio con una carta en la que dispar\u00f3 contra Alberto Fern\u00e1ndez, principalmente por su gesti\u00f3n econ\u00f3mica. Unas pocas horas despu\u00e9s de que se hiciera p\u00fablico dicho documento, comenz\u00f3 ShowMatch y, entre chicanas, Marcelo Tinelli se expres\u00f3 al respecto.<\/p>\n<p>Al comienzo del programa, el hist\u00f3rico conductor del ciclo que se emite por\u00a0eltrece\u00a0hizo una ir\u00f3nica reflexi\u00f3n, en la que comenz\u00f3 diciendo: \u201cEs\u00a0un d\u00eda s\u00faper tranquilo en la Argentina,\u00a0como todos estos que estamos viviendo \u00faltimamente\u201d.<\/p>\n<p>Sin mencionar a nadie ni explicar en concreto a qu\u00e9 se refer\u00eda, apunt\u00f3 \u00e1cidamente contra el Gobierno:\u00a0\u201cLa hacen suave estos muchachos, estas muchachas o muchaches\u201d.\u00a0Y entonces lleg\u00f3 la alusi\u00f3n al texto publicado por la vicepresidenta:\u00a0\u201c\u00a1Mandate una carta!\u201d,\u00a0dispar\u00f3.<\/p>\n<p>Si bien la cr\u00edtica fue clara, Tinelli explic\u00f3 que prefer\u00eda callarse y \u201cno decir nada\u201d, ante lo cual advirti\u00f3: \u201cSi tengo que decir algo, voy a decir una barbaridad\u201d. Y cerr\u00f3:\u00a0\u201cSiempre d\u00e1ndoles tranquilidad a todos, uno se va a dormir tranquilo despu\u00e9s del d\u00eda de hoy\u201d.<\/p>\n<div style=\"width: 696px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-91221-1\" width=\"696\" height=\"392\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/www.cordobatimes.com\/showup\/wp-content\/uploads\/2021\/09\/y2mate.com-Marcelo-Tinelli-hablo-sobre-la-crisis-en-el-Gobierno-Siempre-dandole-tranquilidad-a-todos_1080p.mp4?_=1\" \/><a href=\"https:\/\/www.cordobatimes.com\/showup\/wp-content\/uploads\/2021\/09\/y2mate.com-Marcelo-Tinelli-hablo-sobre-la-crisis-en-el-Gobierno-Siempre-dandole-tranquilidad-a-todos_1080p.mp4\">https:\/\/www.cordobatimes.com\/showup\/wp-content\/uploads\/2021\/09\/y2mate.com-Marcelo-Tinelli-hablo-sobre-la-crisis-en-el-Gobierno-Siempre-dandole-tranquilidad-a-todos_1080p.mp4<\/a><\/video><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El conductor se hizo eco de la crisis interna que vive el oficialismo y critic\u00f3 al Gobierno Tras una serie de d\u00edas \u00e1lgidos en la pol\u00edtica interna del Gobierno, despu\u00e9s de la contundente derrota oficialista en las PASO de las elecciones legislativas, Cristina Kirchner rompi\u00f3 el silencio con una carta en la que dispar\u00f3 contra [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":91222,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[2],"tags":[33398,33397,33399],"class_list":{"0":"post-91221","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tv","8":"tag-carta-de-cristina-kirchner","9":"tag-ironica-frase-de-marcelo-tinelli","10":"tag-marcelo-tinelli-y-cristina-kirchner"},"_links":{"self":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts\/91221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/comments?post=91221"}],"version-history":[{"count":0,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts\/91221\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/media\/91222"}],"wp:attachment":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/media?parent=91221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/categories?post=91221"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/tags?post=91221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}