{"id":90642,"date":"2021-08-02T12:10:54","date_gmt":"2021-08-02T15:10:54","guid":{"rendered":"https:\/\/www.cordobatimes.com\/showup\/?p=90642"},"modified":"2021-08-02T17:17:31","modified_gmt":"2021-08-02T20:17:31","slug":"gaston-pauls-revelo-que-trato-de-ayudar-a-chano-dos-dias-antes-de-que-le-disparen","status":"publish","type":"post","link":"https:\/\/www.cordobatimes.com\/showup\/tv\/2021\/08\/02\/gaston-pauls-revelo-que-trato-de-ayudar-a-chano-dos-dias-antes-de-que-le-disparen\/","title":{"rendered":"Gast\u00f3n Pauls revel\u00f3 que trat\u00f3 de ayudar a Chano dos d\u00edas antes de que le disparen"},"content":{"rendered":"<h3>\u00a0<strong>\u201cHab\u00eda hablado con gente para ver si pod\u00edamos internarlo\u201d<\/strong><\/h3>\n<p>El caso de\u00a0Chano\u00a0Moreno Charpentier\u00a0sigue conmocionando al pa\u00eds. Es que el \u00faltimo domingo, cerca de las 22.50,\u00a0Marina Charpentier, madre del cantante, llam\u00f3 al 911 para pedir asistencia policial en la casa del Barrio Parque La Verdad de Exaltaci\u00f3n de la Cruz, donde\u00a0dos equipos m\u00e9dicos intentaban hac\u00eda casi una hora calmar a su hijo en medio de un episodio de salud mental y derivarlo a un centro\u00a0para ser tratado por sus problemas de adicci\u00f3n. Los tres polic\u00edas de la Comisar\u00eda 2da de la localidad de Parada Robles que se trasladaron al lugar intentaron dialogar sin \u00e9xito con el m\u00fasico, que los enfrent\u00f3 y amenaz\u00f3 con un cuchillo, tras lo cual\u00a0uno de los efectivos de la Polic\u00eda Bonaerense le dispar\u00f3 en el abdomen, hiri\u00e9ndolo gravemente.<\/p>\n<p>En ese marco,\u00a0Gast\u00f3n Pauls, conductor de\u00a0Seres Libres, programa que se trasmite por\u00a0Cr\u00f3nica\u00a0y en el que se entrevistan a reconocidos artistas de nuestro pa\u00eds que atravesaron la adicci\u00f3n, hablo sobre la salud de Chano, que actualmente se encuentra internado en el Sanatorio Otamendi. \u201cDurante esta \u00faltima semana, muchos periodistas me contactaron para hablar en sus medios y yo dije que no por respeto. Porque hay una persona en este momento internada y luchando por su vida. Por respeto a Marina, su madre, y a Chano yo no iba a hablar\u201d, comenz\u00f3 diciendo.<\/p>\n<p>Y luego, agreg\u00f3: \u201cEstoy en contacto con la madre de Chano, desde dos d\u00edas antes de la tragedia,\u00a0me dijo, mientras hablamos, que yo contara en el programa algunas situaciones \u00bfpara qu\u00e9? Para que no haya grietas, para que no haya peleas, porque esta pidiendo aceptaci\u00f3n, ojos abiertos, corazones abiertos de la sociedad, para dejar de tirar culpas a otros, para dejar de tirar la mugre debajo de la alfombra, que es lo que lamentablemente en este pa\u00eds se ha hecho durante d\u00e9cadas y tristemente seguimos haciendo.\u00a0Gracias Marina por esta lucha. Hoy est\u00e1s siendo ejemplo para un mont\u00f3n de padres, hermanos, parejas, de hijos, de hijas, que est\u00e1n sufriendo el consumo y la adicci\u00f3n de un pariente.\u00a0En esta sociedad que se cree absolutamente libre y l\u00f3gica para criticar lo que est\u00e1 haciendo el otro o la otra\u201d.<\/p>\n<p>En ese sentido, cont\u00f3 que trat\u00f3 de internar al ex l\u00edder de\u00a0Tan Bi\u00f3nica\u00a0dos d\u00edas antes de que fuera baleado. \u201cEl s\u00e1bado estaba a punto de entrar al cumplea\u00f1os de un amigo y recibo un mensaje de Marina, que angustiad\u00edsima me ped\u00eda ayuda para ayudar a su hijo quien estaba en una situaci\u00f3n critica desde hac\u00eda unos d\u00edas. Le mand\u00e9 un mensaje a Chano con much\u00edsimo respeto\u00a0porque s\u00e9 que en el consumo siempre hay dolor, paranoia, soledad, desesperaci\u00f3n, ceguera\u201d, relat\u00f3.<\/p>\n<p>Y dio a conocer lo que sucedi\u00f3 despu\u00e9s: \u201cChano me respondi\u00f3 ese mensaje y quedamos en hablar el d\u00eda domingo. Yo hab\u00eda hablado con gente para ver si pod\u00edamos internarlo o acompa\u00f1arlo de alguna manera ese momento crudo que estaba viviendo.\u00a0Los que hemos consumido sabemos que es el infierno el consumo a ese nivel de desesperaci\u00f3n\u201d. \u201cLamentablemente ese llamado no lleg\u00f3 y despu\u00e9s ocurri\u00f3 lo que ocurri\u00f3\u00a0y Marina, quien es una persona hermosa y agradezco la calidad de persona que es, me dec\u00eda: \u2018Compartilo para que el que est\u00e1 del otro lado pueda pedir ayuda porque sino es tarde, pedir ayuda y levantar la mano, porque sino la tragedia est\u00e1 a un cent\u00edmetro de tu vida\u00b4\u201d<\/p>\n<p>Angustiado, Pauls se mostr\u00f3 molesto con las burlas que la gente hizo sobre este tema en las redes sociales. \u201cEste pa\u00eds se ha re\u00eddo un mont\u00f3n de muchas desgracias, no solo de Chano, de otras personas, conocidas y no conocidas.\u00a0Hoy se ponen de moda los memes, haciendo chistes sobre una tragedia, sobre dificultades que puede padecer un ser humano\u201d, cerr\u00f3.<\/p>\n<p><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/T4uwfre0xuw\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0\u201cHab\u00eda hablado con gente para ver si pod\u00edamos internarlo\u201d El caso de\u00a0Chano\u00a0Moreno Charpentier\u00a0sigue conmocionando al pa\u00eds. Es que el \u00faltimo domingo, cerca de las 22.50,\u00a0Marina Charpentier, madre del cantante, llam\u00f3 al 911 para pedir asistencia policial en la casa del Barrio Parque La Verdad de Exaltaci\u00f3n de la Cruz, donde\u00a0dos equipos m\u00e9dicos intentaban hac\u00eda casi [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":90643,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[2],"tags":[33127,33126,33128],"class_list":{"0":"post-90642","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tv","8":"tag-gaston-pauls-chano","9":"tag-gaston-pauls-habla-de-chano","10":"tag-gaston-pauls-habla-de-chano-en-seres-libres"},"_links":{"self":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts\/90642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/comments?post=90642"}],"version-history":[{"count":0,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts\/90642\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/media\/90643"}],"wp:attachment":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/media?parent=90642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/categories?post=90642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/tags?post=90642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}