{"id":90496,"date":"2021-07-26T11:29:08","date_gmt":"2021-07-26T14:29:08","guid":{"rendered":"https:\/\/www.cordobatimes.com\/showup\/?p=90496"},"modified":"2021-07-26T11:29:08","modified_gmt":"2021-07-26T14:29:08","slug":"romanticismo-en-los-juegos-olimpicos-el-es-su-entrenador-y-le-pidio-casamiento-en-una-entrevista-en-vivo","status":"publish","type":"post","link":"https:\/\/www.cordobatimes.com\/showup\/tv\/2021\/07\/26\/romanticismo-en-los-juegos-olimpicos-el-es-su-entrenador-y-le-pidio-casamiento-en-una-entrevista-en-vivo\/","title":{"rendered":"Romanticismo en los Juegos Ol\u00edmpicos:  \u00e9l es su entrenador y le pidi\u00f3 casamiento en  una entrevista en vivo"},"content":{"rendered":"<h3><strong>Est\u00e1n juntos\u00a0hace 18 a\u00f1os no s\u00f3lo en el amor, sino en el trabajo,\u00a0ya que \u00e9l,\u00a0Lucas Saucedo,\u00a0es quien la dirige t\u00e9cnicamente a ella,\u00a0Bel\u00e9n P\u00e9rez Maurice como esgrimista.<\/strong><\/h3>\n<p>Este domingo por la noche, luego de haber perdido en su prueba de sable, la deportista se encontraba dando una entrevista con Gonzalo Bonadeo para TyC Sports en la que reflexionaba sobre su desempe\u00f1o y tambi\u00e9n sobre el pol\u00e9mico arbitraje que hab\u00eda dejado a la vista que la hab\u00edan perjudicado durante el combate que tuvo frente a la atleta h\u00fangara, Anna Marton.<\/p>\n<p>Mientras ella hablaba a c\u00e1mara,\u00a0Lucas apareci\u00f3 en segundo plano con un cartel\u00a0(un papel escrito con fibr\u00f3n negro) en el que dec\u00eda\u00a0\u00abFlaca, te quer\u00e9s casar conmigo\u00bb.\u00a0Leerlo la sac\u00f3 por completo de eje,\u00a0peg\u00f3 un grito de emoci\u00f3n y las l\u00e1grimas\u00a0comenzaron a brotar de sus ojos, aceptando la propuesta de inmediato. Ella no sal\u00eda de su asombro, mientras no dejaba de abrazar a su amor y DT. \u00c9l, emocionado tambi\u00e9n, confes\u00f3 que\u00a0lo hab\u00eda planeado\u00a0y que sent\u00eda una\u00a0profunda admiraci\u00f3n\u00a0por su pareja.<\/p>\n<p>La relaci\u00f3n con Saucedo viene de larga data y estos son los terceros Juegos Ol\u00edmpicos que comparten.\u00a0Mientras transcurr\u00eda este emotivo momento frente a las c\u00e1maras, recordaron que diez a\u00f1os atr\u00e1s ya hab\u00eda habido una propuesta de casamiento que en aquel entonces ella no hab\u00eda aceptado. Ahora, entre risas y emoci\u00f3n, se puso a pensar en el vestido de novia.<\/p>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-90496-1\" width=\"640\" height=\"360\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/www.cordobatimes.com\/showup\/wp-content\/uploads\/2021\/07\/La-esgrimista-Belen-Perez-Maurice-recibio-una-PROPUESTA-DE-CASAMIENTO-de-su-entrenador-Lucas-Sauced.mp4?_=1\" \/><a href=\"https:\/\/www.cordobatimes.com\/showup\/wp-content\/uploads\/2021\/07\/La-esgrimista-Belen-Perez-Maurice-recibio-una-PROPUESTA-DE-CASAMIENTO-de-su-entrenador-Lucas-Sauced.mp4\">https:\/\/www.cordobatimes.com\/showup\/wp-content\/uploads\/2021\/07\/La-esgrimista-Belen-Perez-Maurice-recibio-una-PROPUESTA-DE-CASAMIENTO-de-su-entrenador-Lucas-Sauced.mp4<\/a><\/video><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Est\u00e1n juntos\u00a0hace 18 a\u00f1os no s\u00f3lo en el amor, sino en el trabajo,\u00a0ya que \u00e9l,\u00a0Lucas Saucedo,\u00a0es quien la dirige t\u00e9cnicamente a ella,\u00a0Bel\u00e9n P\u00e9rez Maurice como esgrimista. Este domingo por la noche, luego de haber perdido en su prueba de sable, la deportista se encontraba dando una entrevista con Gonzalo Bonadeo para TyC Sports en la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":90497,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[2],"tags":[33063,33065,33064],"class_list":{"0":"post-90496","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tv","8":"tag-belen-perez-maurice-y-lucas-saucedo","9":"tag-juegos-olimpicos-belen-perez-y-lucas-saucedomaurice","10":"tag-propuesta-de-casamiento-lucas-saucedo-y-belen-perez-maurice"},"_links":{"self":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts\/90496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/comments?post=90496"}],"version-history":[{"count":0,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts\/90496\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/media\/90497"}],"wp:attachment":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/media?parent=90496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/categories?post=90496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/tags?post=90496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}