{"id":90313,"date":"2021-07-14T10:39:43","date_gmt":"2021-07-14T13:39:43","guid":{"rendered":"https:\/\/www.cordobatimes.com\/showup\/?p=90313"},"modified":"2021-07-14T10:39:43","modified_gmt":"2021-07-14T13:39:43","slug":"todos-los-nominados-a-los-premios-emmy-2021","status":"publish","type":"post","link":"https:\/\/www.cordobatimes.com\/showup\/tv\/2021\/07\/14\/todos-los-nominados-a-los-premios-emmy-2021\/","title":{"rendered":"Todos los nominados a los premios Emmy 2021"},"content":{"rendered":"<h3><strong>The Mandalorian&#8217; y &#8216;The Crown&#8217; dominan en las categor\u00edas de drama.<\/strong><\/h3>\n<p>Tenemos una cita el 19 de septiembre para la gala correspondiente a la\u00a073\u00aa edici\u00f3n de los premios Emmy, concedidos por la Academia de la Televisi\u00f3n estadounidense y ya tenemos nominados.<\/p>\n<p>Ron Cephas Jones y su hija Jasmine Cephas Jones, que se llevaron muchas estatuilla el a\u00f1o pasado por &#8216;This is us&#8217; y &#8216;#FreeRyanShawn&#8217; han sido los encargados de develar las nominaciones a las categor\u00edas principales de los premios Emmy 2021. Y, como siempre, alguna sorpresa surgi\u00f3.<\/p>\n<p>Sobre todo en las categor\u00edas principales de comedia, con cosas como &#8216;Emily in Paris&#8217; resurgiendo tras la pol\u00e9mica por los Globos de Oro. Haciendo un recuento de nominaciones, lideran &#8216;The Crown&#8217; y &#8216;The Mandalorian&#8217; con 24 nominaciones cada una, seguidas muy de cerca por &#8216;Bruja Escarlata y Visi\u00f3n&#8217; (23), &#8216;El cuento de la criada&#8217; (21) y &#8216;Saturday Night Live&#8217; (21) completando el top 5.<\/p>\n<p>En cuanto a plataformas HBO\/HBO Max lidera con 130 nominaciones. Netflix 129 y Disney+ completa el podio con 71. A continuaci\u00f3n os dejo la lista completa de nominados.<\/p>\n<h3><strong>Lista de nominados a los premios Emmy 2021<\/strong><\/h3>\n<h3><strong>Comedia<\/strong><\/h3>\n<h3><strong>Mejor actriz principal<\/strong><\/h3>\n<ul>\n<li>Aidy Briant, &#8216;Shrill&#8217;<\/li>\n<li>Kaley Cuoco, &#8216;The Flight Attendant&#8217;<\/li>\n<li>Allison Janney, &#8216;Mom&#8217;<\/li>\n<li>Tracee Ellis Ross, &#8216;Black\u00b7ish&#8217;<\/li>\n<li>Jean Smart, &#8216;Hacks&#8217;<\/li>\n<\/ul>\n<h3><strong>Mejor actor principal<\/strong><\/h3>\n<ul>\n<li>Antohny Anderson, &#8216;Black\u00b7ish&#8217;<\/li>\n<li>Michale Douglas, &#8216;El m\u00e9todo Kominsky&#8217;<\/li>\n<li>William H. Macy, &#8216;Shameless&#8217;<\/li>\n<li>Jason Sudeikis, &#8216;Ted Lasso&#8217;<\/li>\n<li>Kenan Thompson, &#8216;Kenan&#8217;<\/li>\n<\/ul>\n<h3><strong>Mejor actriz de reparto<\/strong><\/h3>\n<ul>\n<li>Aidy Bryant, &#8216;Saturday Night Live&#8217;<\/li>\n<li>Hannah Einbinder, &#8216;Hacks&#8217;<\/li>\n<li>Kate McKinnon, &#8216;Saturday Night Live&#8217;<\/li>\n<li>Rosie Perez, &#8216;The Flight Attendant&#8217;<\/li>\n<li>Cecily Strong, &#8216;Saturday Night Live&#8217;<\/li>\n<li>Juno Temple, &#8216;Ted Lasso&#8217;<\/li>\n<li>Hannah Waddingham, &#8216;Ted Lasso&#8217;<\/li>\n<\/ul>\n<h3><strong>Mejor actor de reparto<\/strong><\/h3>\n<ul>\n<li>Carl Clemons-Hopkins, &#8216;Hacks&#8217;<\/li>\n<li>Brett Goldstein, &#8216;Ted Lasso&#8217;<\/li>\n<li>Brendan Hunt, &#8216;Ted Lasso&#8217;<\/li>\n<li>Nick Mohammed, &#8216;Ted Lasso&#8217;<\/li>\n<li>Paul Reiser, &#8216;El m\u00e9todo Kominsky&#8217;<\/li>\n<li>Kenan Thompson, &#8216;Saturday Night Live&#8217;<\/li>\n<li>Bowen Yang, &#8216;Saturday Night Live&#8217;<\/li>\n<\/ul>\n<h3><strong>Mejor comedia<\/strong><\/h3>\n<ul>\n<li>&#8216;Black\u00b7ish&#8217;<\/li>\n<li>&#8216;Cobra Kai&#8217;<\/li>\n<li>&#8216;Emily in Paris&#8217;<\/li>\n<li>&#8216;Hacks&#8217;<\/li>\n<li>&#8216;The Flight Attendant&#8217;<\/li>\n<li>&#8216;El m\u00e9todo Kominsky&#8217;<\/li>\n<li>&#8216;Pen 15&#8217;<\/li>\n<li>&#8216;Ted Lasso&#8217;<\/li>\n<\/ul>\n<h3><strong>Drama<\/strong><\/h3>\n<h3><strong>Mejor actriz principal<\/strong><\/h3>\n<ul>\n<li>Uzo Aduba, &#8216;En terapia&#8217;<\/li>\n<li>Olivia Colman, &#8216;The Crown&#8217;<\/li>\n<li>Emma Corrin, \u00a0&#8216;The Crown&#8217;<\/li>\n<li>Elisabeth Moss, &#8216;El cuento de la criada&#8217;<\/li>\n<li>Mj Rodriguez, &#8216;Pose&#8217;<\/li>\n<li>Jurnee Smollet, &#8216;Territorio Lovecraft&#8217;<\/li>\n<\/ul>\n<h3><strong>Mejor actor principal<\/strong><\/h3>\n<ul>\n<li>Sterling K. Brown, &#8216;This is Us&#8217;<\/li>\n<li>Jonathan Majors, &#8216;Territorio Lovecraft&#8217;<\/li>\n<li>Josh O&#8217;Connor, &#8216;The Crown&#8217;<\/li>\n<li>Reg\u00e9-Jean Page, &#8216;Los Bridgerton&#8217;<\/li>\n<li>Billy Porter, &#8216;Pose&#8217;<\/li>\n<li>Matthew Rhys, &#8216;Perry Mason&#8217;<\/li>\n<\/ul>\n<h3><strong>Mejor actriz de reparto<\/strong><\/h3>\n<ul>\n<li>Gillian Anderson, &#8216;The Crown&#8217;<\/li>\n<li>Helena Bonham-Carter, &#8216;The Crown&#8217;<\/li>\n<li>Madeline Brewer, &#8216;El cuento de la criada&#8217;<\/li>\n<li>Ann Dowd, &#8216;El cuento de la criada&#8217;<\/li>\n<li>Aunjanue Ellis, &#8216;Territorio Lovecraft&#8217;<\/li>\n<li>Emerald Fennell, &#8216;The Crown&#8217;<\/li>\n<li>Yvonne Strahovski, &#8216;El cuento de la criada&#8217;<\/li>\n<li>Samira Wiley, &#8216;El cuento de la criada&#8217;<\/li>\n<\/ul>\n<h3><strong>Mejor actor de reparto<\/strong><\/h3>\n<ul>\n<li>Giancarlo Esposito, &#8216;The Mandalorian&#8217;<\/li>\n<li>O-T Fagbenle, &#8216;El cuento de la criada&#8217;<\/li>\n<li>John Lithgow, &#8216;Perry Mason&#8217;<\/li>\n<li>Tobias Menzies, &#8216;The Crown&#8217;<\/li>\n<li>Max Minghella, &#8216;El cuento de la criada&#8217;<\/li>\n<li>Chris Sullivan, &#8216;This is Us&#8217;<\/li>\n<li>Bradley Whitford, &#8216;El cuento de la criada&#8217;<\/li>\n<li>Michael K. Williams, &#8216;Territorio Lovecraft&#8217;<\/li>\n<\/ul>\n<h3><strong>Mejor drama<\/strong><\/h3>\n<ul>\n<li>&#8216;The Boys&#8217;<\/li>\n<li>&#8216;Los Bridgerton&#8217;<\/li>\n<li>&#8216;The Crown&#8217;<\/li>\n<li>&#8216;El cuento de la criada&#8217;<\/li>\n<li>&#8216;Territorio Lovecraft&#8217;<\/li>\n<li>&#8216;The Mandalorian&#8217;<\/li>\n<li>&#8216;Pose&#8217;<\/li>\n<li>&#8216;This is Us&#8217;<\/li>\n<\/ul>\n<h3><strong>Series limitadas, antolog\u00edas y pel\u00edculas para televisi\u00f3n<\/strong><\/h3>\n<h3><strong>Mejor actriz principal<\/strong><\/h3>\n<ul>\n<li>Michaela Coel, &#8216;Podr\u00eda destruirte&#8217;<\/li>\n<li>Cynthia Erivo, &#8216;Genius: Aretha&#8217;<\/li>\n<li>Elizabeth Olsen, &#8216;Bruja Escarlata y Visi\u00f3n&#8217;<\/li>\n<li>Anya Taylor-Joy, &#8216;Gambito de Dama&#8217;<\/li>\n<li>Kate Winslet, &#8216;Mare of Easttown&#8217;<\/li>\n<\/ul>\n<h3><strong>Mejor actor principal<\/strong><\/h3>\n<ul>\n<li>Paul Bettany, &#8216;Bruja escarlata y Visi\u00f3n&#8217;<\/li>\n<li>Hugh Grant, &#8216;The Undoing&#8217;<\/li>\n<li>Ewan McGregor, &#8216;Halston&#8217;<\/li>\n<li>Lin-Manuel Miranda, &#8216;Hamilton&#8217;<\/li>\n<li>Lesilie Odom Jr., &#8216;Hamilton&#8217;<\/li>\n<\/ul>\n<h3><strong>Mejor actriz de reparto<\/strong><\/h3>\n<ul>\n<li>Ren\u00e9e Elise Goldsberry, &#8216;Hamilton&#8217;<\/li>\n<li>Kathryn Hahn, &#8216;Bruja Escarlata y Visi\u00f3n&#8217;<\/li>\n<li>Moses Ingram, &#8216;Gambito de dama&#8217;<\/li>\n<li>Julianne Nicholson, &#8216;Mare of Easttown&#8217;<\/li>\n<li>Jean Smart, &#8216;Mare of Easttown&#8217;<\/li>\n<li>Philipa Soo, &#8216;Hamilton&#8217;<\/li>\n<\/ul>\n<h3><strong>Mejor actor de reparto<\/strong><\/h3>\n<ul>\n<li>Thomas Brodie-Sangster, &#8216;Gambito de dama&#8217;<\/li>\n<li>Daveed Diggs, &#8216;Hamilton&#8217;<\/li>\n<li>Paapa Essiedu, &#8216;Podr\u00eda destruirte&#8217;<\/li>\n<li>Jonathan Groff, &#8216;Hamilton&#8217;<\/li>\n<li>Evan Peters, &#8216;Mare of Easttown&#8217;<\/li>\n<li>Anthony Ramos, &#8216;Hamilton&#8217;<\/li>\n<\/ul>\n<h3><strong>Mejor serie limitada o antolog\u00eda<\/strong><\/h3>\n<ul>\n<li>&#8216;Podr\u00eda destruirte&#8217;<\/li>\n<li>&#8216;Mare of Easttown&#8217;<\/li>\n<li>&#8216;Gambito de dama&#8217;<\/li>\n<li>&#8216;El ferrocarril subterr\u00e1neo&#8217;<\/li>\n<li>&#8216;Bruja escarlata y Visi\u00f3n&#8217;<\/li>\n<\/ul>\n<h3><strong>Variedades<\/strong><\/h3>\n<h3><strong>Mejor reality de competici\u00f3n<\/strong><\/h3>\n<ul>\n<li>&#8216;The Amazing Race&#8217;<\/li>\n<li>&#8216;Niquelao!&#8217;<\/li>\n<li>&#8216;RuPaul&#8217;s Drag Race&#8217;<\/li>\n<li>&#8216;Top Chef&#8217;<\/li>\n<li>&#8216;The Voice&#8217;<\/li>\n<\/ul>\n<h3><strong>Mejor talk show<\/strong><\/h3>\n<ul>\n<li>&#8216;Conan&#8217;<\/li>\n<li>&#8216;The Daily Show with Trevor Noah&#8217;<\/li>\n<li>&#8216;Jimmy Kimel Live&#8217;<\/li>\n<li>&#8216;Last Week Tonight with John Oliver&#8217;<\/li>\n<li>&#8216;The Daily Show with Stephen Colbert&#8217;<\/li>\n<\/ul>\n<p>Este a\u00f1o ser\u00e1 la cadena estadounidense CBS, y la plataforma OTT del grupo Paramount+ los encargados de emitir la gala de los Emmy 2021, que\u00a0<strong>ser\u00e1 presentada por Cedric the Entertainment<\/strong>. En Espa\u00f1a, como es habitual, lo veremos a trav\u00e9s de\u00a0Movistar+.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>The Mandalorian&#8217; y &#8216;The Crown&#8217; dominan en las categor\u00edas de drama. Tenemos una cita el 19 de septiembre para la gala correspondiente a la\u00a073\u00aa edici\u00f3n de los premios Emmy, concedidos por la Academia de la Televisi\u00f3n estadounidense y ya tenemos nominados. Ron Cephas Jones y su hija Jasmine Cephas Jones, que se llevaron muchas estatuilla [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":90314,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[2],"tags":[33000,33001],"class_list":{"0":"post-90313","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tv","8":"tag-nominados-a-los-premios-emmy-2021","9":"tag-premios-emmy-2021"},"_links":{"self":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts\/90313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/comments?post=90313"}],"version-history":[{"count":0,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts\/90313\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/media\/90314"}],"wp:attachment":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/media?parent=90313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/categories?post=90313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/tags?post=90313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}