{"id":89618,"date":"2020-12-15T11:14:14","date_gmt":"2020-12-15T14:14:14","guid":{"rendered":"https:\/\/www.cordobatimes.com\/showup\/?p=89618"},"modified":"2020-12-15T11:14:14","modified_gmt":"2020-12-15T14:14:14","slug":"pequena-victoria-obtuvo-el-premio-rose-dor-2020-a-la-mejor-telenovela","status":"publish","type":"post","link":"https:\/\/www.cordobatimes.com\/showup\/tv\/2020\/12\/15\/pequena-victoria-obtuvo-el-premio-rose-dor-2020-a-la-mejor-telenovela\/","title":{"rendered":"\u00abPeque\u00f1a Victoria\u00bb obtuvo el Premio Rose D&#8217;Or 2020 a la mejor telenovela"},"content":{"rendered":"<h3><strong>La tira de Telefe estrenada en 2019 fue reconocida a nivel internacional.<\/strong><\/h3>\n<p>El programa \u201cPeque\u00f1a Victoria\u201d fue ganadora del Premio Rose D&#8217;Or 2020 a la mejor telenovela; as\u00ed lo decidi\u00f3 un jurado de 80 representantes de la industria televisiva mundial.<\/p>\n<p>\u00abEste reconocimiento es un testimonio de todo el equipo dedicado a producir contenido de calidad y reafirma nuestro compromiso de crear\u00a0historias que reflejen la vida real y resalten la diversidad e inclusi\u00f3n de nuestro mundo\u00bb,\u00a0dijo en un comunicado del grupo Federico Cuervo, vicepresidente senior y director de ViacomCBS International Studios (VIS) Americas.<\/p>\n<p>Por su parte, el cineasta\u00a0Daniel Burman,\u00a0director de contenido de The Mediapro Studio US y showrunner de la tira, indic\u00f3 que \u201cestamos orgullosos de los reconocimientos conseguidos por &#8216;Peque\u00f1a Victoria&#8217; y agradecemos mucho al jurado del Premio Rose D&#8217;Or haber premiado este proyecto,\u00a0una propuesta in\u00e9dita que visibiliza nuevos modelos de familias\u00a0y confirma que la diversidad no es un &#8216;trending topic&#8217; m\u00e1s, sino una se\u00f1al (positiva y liberadora) de nuestro tiempo\u00bb.<\/p>\n<p>Recordemos que la tira creada por\u00a0Erika Halvorsen\u00a0y protagonizada por\u00a0Julieta D\u00edaz, Natalie P\u00e9rez, In\u00e9s Est\u00e9vez y Mariana Genesio Pe\u00f1a\u00a0tambi\u00e9n fue nominada a los\u00a0premios\u00a0Emmy Internacional, junto a\u00a0\u00abEl jard\u00edn de bronce\u00bb y \u00abMil manos por Argentina\u00bb.<\/p>\n<p>A ra\u00edz de estos reconocimientos, el holding ratific\u00f3 el inicio de la producci\u00f3n de\u00a0\u201cPeque\u00f1as Victorias, Perdidxs en la Tierra\u201d, nueva temporada que estar\u00e1 disponible en Latinoam\u00e9rica en 2021 a trav\u00e9s de Amazon Prime Video y en Argentina a trav\u00e9s de Telefe.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La tira de Telefe estrenada en 2019 fue reconocida a nivel internacional. El programa \u201cPeque\u00f1a Victoria\u201d fue ganadora del Premio Rose D&#8217;Or 2020 a la mejor telenovela; as\u00ed lo decidi\u00f3 un jurado de 80 representantes de la industria televisiva mundial. \u00abEste reconocimiento es un testimonio de todo el equipo dedicado a producir contenido de calidad [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":89619,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[2],"tags":[32683,32684],"class_list":{"0":"post-89618","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tv","8":"tag-pequena-victoria-premio-rose-dor-2020","9":"tag-premio-rose-dor-2020-a-la-mejor-telenovela"},"_links":{"self":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts\/89618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/comments?post=89618"}],"version-history":[{"count":0,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts\/89618\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/media\/89619"}],"wp:attachment":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/media?parent=89618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/categories?post=89618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/tags?post=89618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}