{"id":88955,"date":"2020-09-16T21:49:09","date_gmt":"2020-09-17T00:49:09","guid":{"rendered":"https:\/\/www.cordobatimes.com\/showup\/?p=88955"},"modified":"2020-09-16T21:49:09","modified_gmt":"2020-09-17T00:49:09","slug":"flor-vigna-se-suma-a-masterchef-celebrity","status":"publish","type":"post","link":"https:\/\/www.cordobatimes.com\/showup\/tv\/2020\/09\/16\/flor-vigna-se-suma-a-masterchef-celebrity\/","title":{"rendered":"Flor Vigna se suma a MasterChef Celebrity"},"content":{"rendered":"<h3><strong>Telefe fue tirando pista acerca de qui\u00e9n es la figura que se incorpora al certamen con famosos.<\/strong><\/h3>\n<p>El nuevo reality culinario de Telefe,\u00a0MasterChef Celebrity\u00a0ya tiene a los concursantes, al jurado y al conductor confirmados. Sin embargo, este mi\u00e9rcoles, desde temprano,\u00a0el canal provoc\u00f3 la intriga de varios al anunciar la incorporaci\u00f3n de una nueva estrella\u00a0a trav\u00e9s de las redes sociales del programa.<\/p>\n<p>Con mensajes inc\u00f3gnitos y una imagen que solo revelaba la silueta de la persona,\u00a0se anunci\u00f3 la llegada de una nueva celebrity. Seg\u00fan las pistas,\u00a0se trataba de una actriz que fue muy pedida por los fans y es la primera vez que ser\u00e1 parte de Telefe.<\/p>\n<p>Vigna se suma al staff de MasterChef, pero no para competir: ser\u00e1 la conductora de los contenidos digitales exclusivos del programa. En la jerga tecnol\u00f3gica le dicen \u00abla host digital\u00bb.<\/p>\n<p>La bailarina y actriz, que\u00a0tiene m\u00e1s de 5 millones de seguidores en Instagram, compartir\u00e1 todo lo que no se ve del ciclo gastron\u00f3mico.\u00a0Mostrar\u00e1 c\u00f3mo es el detr\u00e1s de escena del certamen y recopilar\u00e1 los testimonios\u00a0de cada uno de los participantes, a la hora de hacer un plato y despu\u00e9s de escuchar las devoluciones del jurado, ya sean buenas o malas.<\/p>\n<p>El ciclo tendr\u00e1\u00a016 participantes famosos\u00a0que demostrar\u00e1n su experiencia- o no- en la cocina. El jurado est\u00e1 formado\u00a0por\u00a0Donato De Santis, Germ\u00e1n Martitegui y Dami\u00e1n Betular. Christophe Krywonis fue convocado, pero decidi\u00f3 bajarse.\u00a0Santiago del Moro estar\u00e1 a cargo de la conducci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Telefe fue tirando pista acerca de qui\u00e9n es la figura que se incorpora al certamen con famosos. El nuevo reality culinario de Telefe,\u00a0MasterChef Celebrity\u00a0ya tiene a los concursantes, al jurado y al conductor confirmados. Sin embargo, este mi\u00e9rcoles, desde temprano,\u00a0el canal provoc\u00f3 la intriga de varios al anunciar la incorporaci\u00f3n de una nueva estrella\u00a0a trav\u00e9s [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":88956,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[2],"tags":[32394,32393],"class_list":{"0":"post-88955","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tv","8":"tag-flor-vigna-host-digital","9":"tag-flor-vigna-masterchef-celebrity"},"_links":{"self":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts\/88955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/comments?post=88955"}],"version-history":[{"count":0,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts\/88955\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/media\/88956"}],"wp:attachment":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/media?parent=88955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/categories?post=88955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/tags?post=88955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}