{"id":72919,"date":"2019-12-20T10:08:40","date_gmt":"2019-12-20T13:08:40","guid":{"rendered":"https:\/\/www.cordobatimes.com\/showup\/?p=72919"},"modified":"2019-12-20T10:08:40","modified_gmt":"2019-12-20T13:08:40","slug":"el-contraataque-de-pampita-a-su-ex-ninera-la-denuncio-por-revelar-conversaciones-privadas","status":"publish","type":"post","link":"https:\/\/www.cordobatimes.com\/showup\/famosos\/2019\/12\/20\/el-contraataque-de-pampita-a-su-ex-ninera-la-denuncio-por-revelar-conversaciones-privadas\/","title":{"rendered":"El contraataque  de Pampita a su ex ni\u00f1era: \u00abLa denunci\u00f3 por revelar conversaciones privadas\u00bb"},"content":{"rendered":"<h3><strong>Fernando Burlando revel\u00f3 cu\u00e1l ser\u00e1 la estrategia de la modelo contra Viviana Ben\u00edtez, la mujer que la denunci\u00f3 por \u00abhostigamiento y maltrato psicol\u00f3gico\u00bb.<\/strong><\/h3>\n<p>Ante las fuertes acusaciones de\u00a0Viviana Ben\u00edtez, que incluyeron \u00abhostigamiento y maltrato psicol\u00f3gico\u00bb hasta la p\u00e9rdida de dos embarazos, la respuesta de\u00a0Pampita\u00a0fue clara: se asesor\u00f3 legalmente y contraatac\u00f3.<\/p>\n<p>La conductora de Pampita Online le confi\u00f3 su caso a Fernando Burlando, que ya comunic\u00f3 cu\u00e1l ser\u00e1 su estrategia legal contra la ex ni\u00f1era de su defendida.<\/p>\n<p>A Viviana, que ya tiene un bozal legal, Carolina le iniciar\u00e1 una querella. \u00abEste tema est\u00e1 estudiado y se va a iniciar una querella por calumnias e injurias. Tambi\u00e9n la denunci\u00f3 en la justicia, por esta situaci\u00f3n de revelar temas de la intimidad y conversaciones que no ten\u00edan que tomar estado p\u00fablico. Y adem\u00e1s, no descartamos la posibilidad de denunciar penalmente otro tipo de situaci\u00f3n\u00bb, le cont\u00f3 a\u00a0Mariana Calabr\u00f3\u00a0en\u00a0El diario de Mariana.<\/p>\n<p>\u00bfA qu\u00e9 se refiere con temas de la intimidad? Especialmente, a que Ben\u00edtez detall\u00f3 c\u00f3mo ser\u00edan sus\u00a0fuert\u00edsimas peleas\u00a0con\u00a0Roberto Garc\u00eda Morit\u00e1n.<\/p>\n<p>Burlando cerr\u00f3 remarcando que la situaci\u00f3n es muy injusta para su clienta: \u00abEn todo esto hay una gran cuota de traici\u00f3n\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fernando Burlando revel\u00f3 cu\u00e1l ser\u00e1 la estrategia de la modelo contra Viviana Ben\u00edtez, la mujer que la denunci\u00f3 por \u00abhostigamiento y maltrato psicol\u00f3gico\u00bb. Ante las fuertes acusaciones de\u00a0Viviana Ben\u00edtez, que incluyeron \u00abhostigamiento y maltrato psicol\u00f3gico\u00bb hasta la p\u00e9rdida de dos embarazos, la respuesta de\u00a0Pampita\u00a0fue clara: se asesor\u00f3 legalmente y contraatac\u00f3. La conductora de Pampita Online [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":72920,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","footnotes":""},"categories":[4],"tags":[27329,27330,27098],"class_list":["post-72919","post","type-post","status-publish","format-standard","has-post-thumbnail","category-famosos","tag-contraataque-de-pampita-a-su-ex-ninera","tag-pampita-ex-ninera","tag-pampita-viviana-benitez"],"_links":{"self":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts\/72919","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/comments?post=72919"}],"version-history":[{"count":0,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts\/72919\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/media\/72920"}],"wp:attachment":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/media?parent=72919"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/categories?post=72919"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/tags?post=72919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}