{"id":70637,"date":"2019-11-27T13:55:23","date_gmt":"2019-11-27T16:55:23","guid":{"rendered":"https:\/\/www.cordobatimes.com\/showup\/?p=70637"},"modified":"2019-11-27T13:55:23","modified_gmt":"2019-11-27T16:55:23","slug":"morfi-se-despide-de-la-television-tras-cinco-temporadas","status":"publish","type":"post","link":"https:\/\/www.cordobatimes.com\/showup\/tv\/2019\/11\/27\/morfi-se-despide-de-la-television-tras-cinco-temporadas\/","title":{"rendered":"Morfi se despide de la televisi\u00f3n, tras cinco temporadas"},"content":{"rendered":"<h3><strong>Luego de cinco exitosas temporadas y m\u00e1s de mil programas,\u00a0Morfi, todos a la mesa\u00a0se despide de la pantalla de\u00a0Telefe.\u00a0<\/strong><\/h3>\n<p>El programa conducido por Chino Leunis y Zaira Nara tendr\u00eda su \u00faltimo programa el viernes 27 de diciembre.<\/p>\n<p>En los pasillos del canal se especula con la posibilidad de que Zaira no est\u00e9 presente ya que est\u00e1 embarazada de poco m\u00e1s de siete meses y tiene fecha probable de parto para mediados de enero. Por su parte, Leunis s\u00ed estar\u00e1 en la gran despedida del ciclo y, actualmente, se encuentra negociando su contrato para 2020, en el que se podr\u00eda al frente de un nuevo proyecto.<\/p>\n<p>Por el momento, la grilla del verano no ha sido definida por lo que todav\u00eda no est\u00e1 definido qu\u00e9 proyecto reemplazar\u00e1 a Morfi. \u201cNo se termina ni por el embarazo de Zai, ni por la propuesta del Chino, ni por rating. M\u00e1s que nada es un ciclo cumplido, ya super\u00f3 los mil programas\u201d, explicaron\u00a0 fuentes cercanas a la producci\u00f3n.<\/p>\n<p>Morfi, todos a la mesa debut\u00f3 el d\u00eda lunes 29 de junio de 2015 y por su estudio pasaron m\u00e1s de 3500 invitados. El pasado 5 de agosto, el ciclo celebr\u00f3 sus 1000 emisiones y fue tal su \u00e9xito que el programa tuvo varios desprendimientos como\u00a0La pe\u00f1a de Morfi, Morfi Kids, Morfi Caf\u00e9, Especiales musicales de Morfi\u00a0y\u00a0La fiesta de Morfi.<\/p>\n<p>En cinco temporadas, cont\u00f3 con diversos figuras como\u00a0Gerardo Roz\u00edn, Dami\u00e1n De Santo\u00a0y\u00a0Carina Zampini\u00a0en la conducci\u00f3n, y\u00a0Malena Ginzburg, Mar\u00eda Bel\u00e9n Aramburu, Ariel Rodr\u00edguez, Connie Ansaldi, Paulo Kablan\u00a0y\u00a0Melina Fleiderman\u00a0como panelistas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luego de cinco exitosas temporadas y m\u00e1s de mil programas,\u00a0Morfi, todos a la mesa\u00a0se despide de la pantalla de\u00a0Telefe.\u00a0 El programa conducido por Chino Leunis y Zaira Nara tendr\u00eda su \u00faltimo programa el viernes 27 de diciembre. En los pasillos del canal se especula con la posibilidad de que Zaira no est\u00e9 presente ya que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":70638,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[2],"tags":[26171,26170],"class_list":{"0":"post-70637","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tv","8":"tag-chino-leunis-y-zaira-nara","9":"tag-morfi-todos-a-la-mesa-telefe"},"_links":{"self":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts\/70637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/comments?post=70637"}],"version-history":[{"count":0,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts\/70637\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/media\/70638"}],"wp:attachment":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/media?parent=70637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/categories?post=70637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/tags?post=70637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}