{"id":69688,"date":"2019-11-19T12:02:00","date_gmt":"2019-11-19T15:02:00","guid":{"rendered":"https:\/\/www.cordobatimes.com\/showup\/?p=69688"},"modified":"2019-11-19T12:02:00","modified_gmt":"2019-11-19T15:02:00","slug":"la-foto-inedita-del-elenco-del-chavo-del-8","status":"publish","type":"post","link":"https:\/\/www.cordobatimes.com\/showup\/tv\/2019\/11\/19\/la-foto-inedita-del-elenco-del-chavo-del-8\/","title":{"rendered":"La foto in\u00e9dita del elenco del \u201cChavo del 8\u201d"},"content":{"rendered":"<h3><strong>La imagen fue compartida por el nieto de \u201cDon Ram\u00f3n\u201d.\u00a0<\/strong><\/h3>\n<p>Cada vez que sale alguna noticia, imagen o comentario sobre el detr\u00e1s de escena de la m\u00edtica serie El Chavo del 8, todos est\u00e1n interesados en saber m\u00e1s.<\/p>\n<p>Los romances, los odios y todas las historias que se entretejieron alrededor de este cl\u00e1sico de la televisi\u00f3n mejicana que se volvi\u00f3 tambi\u00e9n un cl\u00e1sico en el resto de Latinoam\u00e9rica, generan mucha curiosidad y alimentan suspicacias.<\/p>\n<p>En este caso el nieto del actor que interpretaba al entra\u00f1able Don Ram\u00f3n, comparti\u00f3 una foto del elenco que encontr\u00f3 entre las pertenencias familiares.<\/p>\n<p>Adem\u00e1s de Ram\u00f3n Vald\u00e9s, se puede ver a Carlos Villagr\u00e1n caracterizado como \u201cQuico\u201d, Roberto G\u00f3mez Bola\u00f1os, con la cl\u00e1sica gorra del \u201cChavo\u201d y Rub\u00e9n Aguirre vestido como se vest\u00eda \u201cEl Profesor Jirafales\u201d.<\/p>\n<p>\u201c\u00a1Una foto in\u00e9dita! La verdad no s\u00e9 d\u00f3nde se tom\u00f3, pero parece que es la casa de alguno de los miembros del elenco, \u00bfalguien sabe qui\u00e9nes son los dem\u00e1s? A ver qui\u00e9n de elenco est\u00e1 en la foto \ud83d\ude42 abrazos a todos (sic)\u201d, dijo Ram\u00f3n Vald\u00e9s Castillo, nieto del actor fallecido en 1988.<\/p>\n<p>A pocas horas de compartida, la imagen se volvi\u00f3 viral y recibi\u00f3 miles de \u201cme gusta\u201d y cientos de comentarios.<\/p>\n<blockquote class=\"twitter-tweet\" data-lang=\"es\">\n<p lang=\"es\" dir=\"ltr\">Una foto in\u00e9dita! La verdad no se donde se tom\u00f3! Pero parece que es la casa de alguno de los miembros del elenco, alguien sabe quienes son los dem\u00e1s? A ver quien de elenco est\u00e1 en la foto \ud83d\ude42 abrazos a todos <a href=\"https:\/\/t.co\/RGP3BzqJGl\">pic.twitter.com\/RGP3BzqJGl<\/a><\/p>\n<p>&mdash; Ram\u00f3n Vald\u00e9s Castillo (@RamnValdsCasti1) <a href=\"https:\/\/twitter.com\/RamnValdsCasti1\/status\/1195143941248565248?ref_src=twsrc%5Etfw\">15 de noviembre de 2019<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La imagen fue compartida por el nieto de \u201cDon Ram\u00f3n\u201d.\u00a0 Cada vez que sale alguna noticia, imagen o comentario sobre el detr\u00e1s de escena de la m\u00edtica serie El Chavo del 8, todos est\u00e1n interesados en saber m\u00e1s. Los romances, los odios y todas las historias que se entretejieron alrededor de este cl\u00e1sico de la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":69689,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[2],"tags":[25764,25765],"class_list":{"0":"post-69688","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tv","8":"tag-elenco-del-chavo-del-8","9":"tag-foto-inedita-chavo-del-8"},"_links":{"self":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts\/69688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/comments?post=69688"}],"version-history":[{"count":0,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts\/69688\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/media\/69689"}],"wp:attachment":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/media?parent=69688"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/categories?post=69688"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/tags?post=69688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}