{"id":69611,"date":"2019-11-16T11:47:12","date_gmt":"2019-11-16T14:47:12","guid":{"rendered":"https:\/\/www.cordobatimes.com\/showup\/?p=69611"},"modified":"2019-11-16T11:47:12","modified_gmt":"2019-11-16T14:47:12","slug":"no-habra-almuerzos-de-mirtha-desde-la-feliz-esta-temporada","status":"publish","type":"post","link":"https:\/\/www.cordobatimes.com\/showup\/tv\/2019\/11\/16\/no-habra-almuerzos-de-mirtha-desde-la-feliz-esta-temporada\/","title":{"rendered":"No habr\u00e1 Almuerzos de Mirtha desde \u00abLa Feliz\u00bb esta temporada"},"content":{"rendered":"<h3><strong>La producci\u00f3n de la Chiqui confirm\u00f3 que esta temporada no habr\u00e1 emisi\u00f3n de los tradicionales almuerzos en Mar del Plata. Todos los detalles sobre los motivos de esta decisi\u00f3n.<\/strong><\/h3>\n<p>Los tradicionales almuerzos en las costas de MDQ ser\u00e1n interrumpidos este verano, luego de numerosas reuniones entre la producci\u00f3n del ciclo televisivo de Mirtha Legrand y las autoridades de El Trece. Adem\u00e1s, se inform\u00f3 que <strong>tampoco habr\u00e1 almuerzos o cenas en Buenos Aires<\/strong>, por lo que la conductora retomar\u00eda su actividad reci\u00e9n en marzo 2020.<\/p>\n<p>De manera contundente e irreversible, por primera vez en muchos a\u00f1os, la diva no contar\u00e1 con espacio en el aire. \u201cTodo <strong>tiene que ver con un tema de presupuesto<\/strong>. Tampoco sigue en Buenos Aires porque hay un costo del alquiler de los estudios\u201d, explic\u00f3 Carlos Monti en \u201cPamela a la tarde\u201d; y se descartaron los rumores que circulaban respecto a problemas de salud de la Chiqui.<\/p>\n<p>\u201cEn los \u00faltimos a\u00f1os hubo un gran a<strong>poyo publicitario de la provincia con lo que ten\u00eda que ver con promocionar Mar del Plata<\/strong>. Con un nuevo gobierno es muy dif\u00edcil ponerse a proyectar y cerrar para este verano en tan poco tiempo\u201d, agreg\u00f3 Pablo Layus en el programa conducido por Pamela David.<\/p>\n<p>La conductora no se pronunci\u00f3 al respecto pero es, sin dudas,\u00a0<strong>una noticia desconcertante para toda la producci\u00f3n<\/strong>, luego de que Legrand expresara en los \u00faltimos d\u00edas que trabajar\u00eda \u201cgratis\u201d con tal de no interrumpir la programaci\u00f3n en La Feliz:\u00a0\u201cYo dejar\u00eda de cobrar mi sueldo con tal de ir. Mir\u00e1 lo que estoy diciendo\u2026\u201d, hab\u00eda explicado\u00a0<strong>la conductora de 92 a\u00f1os.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La producci\u00f3n de la Chiqui confirm\u00f3 que esta temporada no habr\u00e1 emisi\u00f3n de los tradicionales almuerzos en Mar del Plata. Todos los detalles sobre los motivos de esta decisi\u00f3n. Los tradicionales almuerzos en las costas de MDQ ser\u00e1n interrumpidos este verano, luego de numerosas reuniones entre la producci\u00f3n del ciclo televisivo de Mirtha Legrand y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":69612,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[2],"tags":[25731],"class_list":{"0":"post-69611","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tv","8":"tag-mirtha-legrand-mar-del-plata-2020"},"_links":{"self":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts\/69611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/comments?post=69611"}],"version-history":[{"count":0,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts\/69611\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/media\/69612"}],"wp:attachment":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/media?parent=69611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/categories?post=69611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/tags?post=69611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}