{"id":68954,"date":"2019-11-11T12:03:07","date_gmt":"2019-11-11T15:03:07","guid":{"rendered":"https:\/\/www.cordobatimes.com\/showup\/?p=68954"},"modified":"2019-11-11T12:03:07","modified_gmt":"2019-11-11T15:03:07","slug":"mirko-y-marley-visitaron-a-susana-gimenez","status":"publish","type":"post","link":"https:\/\/www.cordobatimes.com\/showup\/tv\/2019\/11\/11\/mirko-y-marley-visitaron-a-susana-gimenez\/","title":{"rendered":"Mirko y Marley visitaron a Susana Gim\u00e9nez"},"content":{"rendered":"<h3><strong>El peque\u00f1o jug\u00f3 con los regalos que le hizo su madrina, quien cometi\u00f3 uno de sus cl\u00e1sicos bloopers en medio de la charla.<\/strong><\/h3>\n<p>El living de Susana Gim\u00e9nez tuvo este domingo dos visitas muy especiales: su ahijado, Mirko, y su gran amigo Marley estuvieron con la diva. En una charla distendida, los conductores revivieron sus mejores an\u00e9cdotas de viajes y, por supuesto, hablaron de la vida de la peque\u00f1a estrella, que acaba de cumplir dos a\u00f1os.<\/p>\n<p>La producci\u00f3n del programa de la Su recibi\u00f3 a Mirko con una caja llena de juguetes, en donde primaban los autos y las pelotas. El peque\u00f1o se puso a jugar, casi como si estuviera en su casa, sin registrar las luces y las c\u00e1maras de televisi\u00f3n. Aunque Marley se\u00f1al\u00f3 que era todo nuevo para \u00e9l, ya que era la primera vez que pisaba un estudio tan grande en vivo: \u201cSolo vino una vez a Minuto para Ganar, pero era un programa grabado, donde entr\u00f3, me salud\u00f3 y se fue\u201d. El conductor incluso resalt\u00f3 que le sorprendi\u00f3 la respuesta de su hijo, ya que pens\u00f3 que se iba a poner a llorar.<\/p>\n<p>Mientras Mirko jugaba, Susana y Marley repasaron algunas an\u00e9cdotas, e hicieron hincapi\u00e9 en el viaje que realizaron este a\u00f1o a Sidney, cuando la diva se tuvo que subir al puente m\u00e1s alto del mundo, a pesar de sus problemas en la r\u00f3tula; o la vez en la que tuvo un furcio antes de asistir a un musical de Ludwig van Beethoven Beethoven. \u201c\u00bfToca Bethooven?\u00bb, hab\u00eda preguntado la diva en aquella oportunidad, seg\u00fan revelaron. \u00abFue peor que la an\u00e9cdota del dinosaurio\u201d, confes\u00f3, entre risas, Marley.<\/p>\n<p>Aunque la an\u00e9cdota m\u00e1s divertida tuvo lugar en su viaje a Nueva York, cuando fueron a bautizar a Mirko. \u201cLa llevamos (a Susana) a un restaurante caro pero le hicimos pagar la mitad de la cuenta porque nos iban a matar, era un delirio el lugar. Pero la culpa fue de Susana, se pidi\u00f3 el vino m\u00e1s caro\u201d, dijo el conductor de Por el Mundo. La diva asinti\u00f3: \u201cYo qu\u00e9 sab\u00eda, encima todos tomaron el mismo vino: pagamos 10 mil d\u00f3lares de vino\u201d.<\/p>\n<p>\u201c\u00bfEs cierto que en el 2020 quer\u00e9s buscar un hermanito para Mirko?\u201d, lo sorprendi\u00f3 Susana a su amigo con la pregunta. Pero Marley se\u00f1al\u00f3 que aunque tiene ganas lo est\u00e1 evaluando: \u201cEs mucho el trabajo, nadie te avisa lo que pasa. Lo amo pero es s\u00faper intenso el cuidado que necesita. Me hace tirar al piso y yo ya estoy viejo para eso. Tengo tres personas que me ayudan con \u00e9l, no se c\u00f3mo hacen las personas que est\u00e1n sin ayuda con los chicos\u201d.<\/p>\n<p>En medio de la entrevista, Mirko comenz\u00f3 a correr por el estudio e incluso intent\u00f3 salir del estudio por la puerta que hab\u00edan entrado. En un hecho in\u00e9dito, Susana se levant\u00f3 del sill\u00f3n del living y fue a buscar al peque\u00f1o. \u201cSe est\u00e1 robando el cami\u00f3n\u201d, se\u00f1al\u00f3 Marley muy divertido.<\/p>\n<p>Cuando lograron que el peque\u00f1o regresara, continu\u00f3 la entrevista y Marley revel\u00f3 que le habla en tres idiomas a Mirko -espa\u00f1ol, ingl\u00e9s y alem\u00e1n-, y que el ni\u00f1o ya identifica los n\u00fameros en todos los dialectos. \u201cLa inteligencia no es m\u00eda, la sac\u00f3 de la parte biol\u00f3gica rusa\u201d, dijo, entre risas. Tambi\u00e9n sostuvo que el a\u00f1o que viene comenzar\u00e1 el jard\u00edn en una escuela triling\u00fce, y que a\u00fan no sabe si ser\u00e1 en febrero o en julio, ya que depender\u00e1 de los viajes de su programa.<\/p>\n<p>El conductor cont\u00f3 que Mirko tiene un pasaporte inusual para su edad: \u201cTiene sellos de Jap\u00f3n, Alemania, Rusia, China. Cuando llegamos a los pa\u00edses corren las hojas y se preguntan c\u00f3mo puede ser que estuvo en tantos lugares en tan poco tiempo: nadie entiende que un bebe tenga tantos sellos\u201d.<\/p>\n<p>Marley y Susana revivieron los momentos del nacimiento de Mirko. \u201cEstaba solo, se adelant\u00f3, estaba nervioso&#8230; Le daba la mano a Brittany\u00bb, revel\u00f3, en referencia a la gestante de Mirko. Pero Susana, en medio de la emoci\u00f3n, realiz\u00f3 un comentario inesperado: mientas mostraban im\u00e1genes de la mujer, la diva pregunt\u00f3 si estaba \u201cembarazada de nuevo\u201d. Marley lo neg\u00f3, en medio de una risa nerviosa.<\/p>\n<p>Pero quiz\u00e1s lo m\u00e1s llamativo fue cuando el conductor cont\u00f3 que Mirko tiene una cuenta bancaria propia: \u00abTodo lo que gana va a una cuenta, cuando sea adulto va a recibir todo. La verdad es que nos desbord\u00f3 lo que pas\u00f3 con \u00e9l, yo no sab\u00eda lo que iba a pasar con el p\u00fablico, hay marcas importantes que quieren hacer publicidades con \u00e9l, entonces cuando sea adulto decidir\u00e1 lo que quiere hacer\u201d.<\/p>\n<p>Mirko naci\u00f3 el 27 de octubre de 2017. Midi\u00f3 51 cent\u00edmetros y pes\u00f3 3,200 kgs. A ra\u00edz de las publicaciones que el conductor hace en sus redes sociales, y porque siempre viajan juntos en Por el Mundo, el peque\u00f1o no tard\u00f3 en convertirse en una aut\u00e9ntica celebridad y ya super\u00f3 los cuatro millones de seguidores en su cuenta en Instagram.<\/p>\n<p><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/B347LxplG2A\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/tyBzSrO1bO8\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/wI6wl7eTqrc\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El peque\u00f1o jug\u00f3 con los regalos que le hizo su madrina, quien cometi\u00f3 uno de sus cl\u00e1sicos bloopers en medio de la charla. El living de Susana Gim\u00e9nez tuvo este domingo dos visitas muy especiales: su ahijado, Mirko, y su gran amigo Marley estuvieron con la diva. En una charla distendida, los conductores revivieron sus [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":68955,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[2],"tags":[25527,25528],"class_list":{"0":"post-68954","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tv","8":"tag-mirko-y-marley","9":"tag-mirko-y-marley-susana-gimenez"},"_links":{"self":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts\/68954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/comments?post=68954"}],"version-history":[{"count":0,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts\/68954\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/media\/68955"}],"wp:attachment":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/media?parent=68954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/categories?post=68954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/tags?post=68954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}