{"id":65659,"date":"2019-07-27T11:38:22","date_gmt":"2019-07-27T14:38:22","guid":{"rendered":"https:\/\/www.cordobatimes.com\/showup\/?p=65659"},"modified":"2019-07-27T11:38:22","modified_gmt":"2019-07-27T14:38:22","slug":"los-escritores-de-los-simpson-revelaron-como-predicen-el-futuro","status":"publish","type":"post","link":"https:\/\/www.cordobatimes.com\/showup\/tv\/2019\/07\/27\/los-escritores-de-los-simpson-revelaron-como-predicen-el-futuro\/","title":{"rendered":"Los escritores de Los Simpson revelaron c\u00f3mo \u201cpredicen\u201d el futuro"},"content":{"rendered":"<h3><strong>La serie ha tenido aciertos tan divertidos como escalofriantes. Al Jean, guionista hist\u00f3rico, cont\u00f3 el \u201ctruco\u201d.<\/strong><\/h3>\n<p>Desde que Donald Trump ser\u00eda el presidente de Estados Unidos, hasta el regreso del \u00c9bola, los smartphones o Lady Gaga cantando en el Superbowl.<\/p>\n<p>Todos los sabemos:\u00a0Los Simpson\u00a0le \u201chan pegado\u201d con su s\u00e1tira e imaginaci\u00f3n a muchos hechos que luego con el paso del tiempo se terminaron convirtiendo en realidad.<\/p>\n<p>Al Jean, escritor hist\u00f3rico de la tira amarilla (est\u00e1 desde su comienzo, en 1989) y su pareja, la tambi\u00e9n guionista de\u00a0Los Simpson\u00a0Stephanie Gillis, brindaron una entrevista a\u00a0BBC Radio 1 Newsbeat\u00a0y contaron c\u00f3mo parte del proceso creativo incide en esta cuesti\u00f3n.<\/p>\n<p>En primera instancia, el equipo de creativos y escritores est\u00e1 constantemente atento a lo que sucede en el mundo actual, y lo usan como base para plantear situaciones hilarantes dentro del universo simpsoniano.<\/p>\n<p>El resto es hacer muchas predicciones: si funcionan ser\u00e1n graciosas, y si luego encima se convierten en realidad, pasar\u00e1n a ser titulares en todos los medios.<\/p>\n<h3><strong>Cuesti\u00f3n de probabilidades<\/strong><\/h3>\n<p>\u201cSi hac\u00e9s la suficiente cantidad de predicciones, es muy probable que el 10 por ciento de ellas terminen convirti\u00e9ndose en realidad\u201d, dijo Al.<\/p>\n<p>\u201cSomos una suerte de futur\u00f3logos en el sentido de que escribimos pensando a 10 meses en adelante (para cuando el episodio salga al aire), as\u00ed que intentamos adivinar qu\u00e9 es lo que pasar\u00e1\u201d, agreg\u00f3 Gillis.<\/p>\n<p>\u201cCuando pusimos a Trump como presidente, en el a\u00f1o 2000, est\u00e1bamos buscando alguna celebridad graciosa ocupando el cargo\u201d, grafic\u00f3 Jean. Igualmente, no era un disparate: el por entonces magnate inmobiliario ya hab\u00eda manifestado su idea de embarcarse en la carrera a presidente en el futuro.<\/p>\n<h3><strong>Teor\u00edas conspiran\u00f3icas<\/strong><\/h3>\n<p>Claro que estos aciertos incluso han generado el terreno ideal para los amantes de las teor\u00edas conspirativas.<\/p>\n<p>Un cap\u00edtulo muy recordado es el titulado\u00a0La ciudad de Nueva York contra Homero Simpson, con la visita de la familia amarilla a la Gran Manzana.<\/p>\n<p><img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-65661\" src=\"https:\/\/www.cordobatimes.com\/showup\/wp-content\/uploads\/2019\/07\/image_1564186347.jpg\" alt=\"\" width=\"1020\" height=\"560\" srcset=\"https:\/\/www.cordobatimes.com\/showup\/wp-content\/uploads\/2019\/07\/image_1564186347.jpg 1020w, https:\/\/www.cordobatimes.com\/showup\/wp-content\/uploads\/2019\/07\/image_1564186347-760x417.jpg 760w, https:\/\/www.cordobatimes.com\/showup\/wp-content\/uploads\/2019\/07\/image_1564186347-750x412.jpg 750w, https:\/\/www.cordobatimes.com\/showup\/wp-content\/uploads\/2019\/07\/image_1564186347-768x422.jpg 768w, https:\/\/www.cordobatimes.com\/showup\/wp-content\/uploads\/2019\/07\/image_1564186347-696x382.jpg 696w, https:\/\/www.cordobatimes.com\/showup\/wp-content\/uploads\/2019\/07\/image_1564186347-765x420.jpg 765w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/><\/p>\n<p>\u201cAh\u00ed compran una gu\u00eda tur\u00edstica de la ciudad que ten\u00eda escrito \u20189 d\u00f3lares\u2019 al lado de un dibujo de las Torres Gemelas, cosa que muchos vieron como 9\/11\u201d, explica Al, en referencia al ataque terrorista al coraz\u00f3n de Manhattan. \u201cEso fue pura coincidencia\u201d, asegur\u00f3 el escritor.<\/p>\n<p>En otros casos, por ejemplo, fueron carne de\u00a0fake news, como el famoso meme en el que se ve a Trump junto a otros l\u00edderes mundiales apoyando su mano en una esfera iluminada.<\/p>\n<p><img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-65662\" src=\"https:\/\/www.cordobatimes.com\/showup\/wp-content\/uploads\/2019\/07\/1221-1_1564186271.jpg\" alt=\"\" width=\"525\" height=\"657\" srcset=\"https:\/\/www.cordobatimes.com\/showup\/wp-content\/uploads\/2019\/07\/1221-1_1564186271.jpg 525w, https:\/\/www.cordobatimes.com\/showup\/wp-content\/uploads\/2019\/07\/1221-1_1564186271-336x420.jpg 336w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/p>\n<p>La imagen se viraliz\u00f3 como que el episodio hab\u00eda ocurrido en 2002, cuando no era cierto: sali\u00f3 el 26 de mayo de 2017 en la p\u00e1gina de Facebook de la serie, despu\u00e9s de que el presidente estadounidense visitara Arabia Saudita y efectivamente se tomara esa foto. Internet populariz\u00f3 la versi\u00f3n falsa.<\/p>\n<p>Tambi\u00e9n se dieron casos contrarios, en los que la tira fue \u00abparodiada\u00bb por personajes reales, como la propia Lady Gaga y su actuaci\u00f3n en el Superbowl, que tuvo gui\u00f1os hacia la versi\u00f3n animada.<\/p>\n<p><img alt=\"\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-65663\" src=\"https:\/\/www.cordobatimes.com\/showup\/wp-content\/uploads\/2019\/07\/58_1564186233.jpg\" alt=\"\" width=\"1020\" height=\"560\" srcset=\"https:\/\/www.cordobatimes.com\/showup\/wp-content\/uploads\/2019\/07\/58_1564186233.jpg 1020w, https:\/\/www.cordobatimes.com\/showup\/wp-content\/uploads\/2019\/07\/58_1564186233-760x417.jpg 760w, https:\/\/www.cordobatimes.com\/showup\/wp-content\/uploads\/2019\/07\/58_1564186233-750x412.jpg 750w, https:\/\/www.cordobatimes.com\/showup\/wp-content\/uploads\/2019\/07\/58_1564186233-768x422.jpg 768w, https:\/\/www.cordobatimes.com\/showup\/wp-content\/uploads\/2019\/07\/58_1564186233-696x382.jpg 696w, https:\/\/www.cordobatimes.com\/showup\/wp-content\/uploads\/2019\/07\/58_1564186233-765x420.jpg 765w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/><\/p>\n<p>En definitiva, el curioso talento de los guionistas para acertar al futuro tiene m\u00e1s que ver con el trabajo y la casualidad que con predicciones fant\u00e1sticas.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La serie ha tenido aciertos tan divertidos como escalofriantes. Al Jean, guionista hist\u00f3rico, cont\u00f3 el \u201ctruco\u201d. Desde que Donald Trump ser\u00eda el presidente de Estados Unidos, hasta el regreso del \u00c9bola, los smartphones o Lady Gaga cantando en el Superbowl. Todos los sabemos:\u00a0Los Simpson\u00a0le \u201chan pegado\u201d con su s\u00e1tira e imaginaci\u00f3n a muchos hechos que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":65660,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[2],"tags":[24172,24173],"class_list":{"0":"post-65659","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tv","8":"tag-escritores-de-los-simpson","9":"tag-escritores-de-los-simpson-predicen-el-futuro"},"_links":{"self":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts\/65659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/comments?post=65659"}],"version-history":[{"count":0,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts\/65659\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/media\/65660"}],"wp:attachment":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/media?parent=65659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/categories?post=65659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/tags?post=65659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}