{"id":65258,"date":"2019-06-15T11:08:59","date_gmt":"2019-06-15T14:08:59","guid":{"rendered":"https:\/\/www.cordobatimes.com\/showup\/?p=65258"},"modified":"2019-06-15T11:09:49","modified_gmt":"2019-06-15T14:09:49","slug":"ines-estevez-y-julieta-diaz-protagonizaran-pequena-victoria-por-telefe","status":"publish","type":"post","link":"https:\/\/www.cordobatimes.com\/showup\/tv\/2019\/06\/15\/ines-estevez-y-julieta-diaz-protagonizaran-pequena-victoria-por-telefe\/","title":{"rendered":"In\u00e9s Est\u00e9vez  y Julieta D\u00edaz protagonizar\u00e1n \u00abPeque\u00f1a Victoria\u00bb, por Telefe"},"content":{"rendered":"<h3><strong>Un alquiler de vientre y un nacimiento unen a cuatro mujeres en Peque\u00f1a Victoria.<\/strong><\/h3>\n<p>Viacom Internacional comenz\u00f3 el rodaje de la nueva comedia dram\u00e1tica Peque\u00f1a Victoria, protagonizada por Julieta D\u00edaz, Natalie P\u00e9rez, In\u00e9s Est\u00e9vez y Mariana Genesio, y que se ver\u00e1 en el segundo semestre del a\u00f1o por Telefe.<\/p>\n<p>Peque\u00f1a Victoria\u00a0comienza con el nacimiento de un beb\u00e9, que unir\u00e1 los caminos de cuatro mujeres muy diferentes pero con un denominador com\u00fan: el amor por la peque\u00f1a. Jazm\u00edn (D\u00edaz) es una ejecutiva exitosa de casi 40 a\u00f1os que subrog\u00f3 -de manera clandestina- el vientre de B\u00e1rbara (P\u00e9rez) para poder ser madre, sin que el embarazo perjudique su carrera corporativa en pleno ascenso. B\u00e1rbara, por su parte, alquil\u00f3 su vientre a cambio de una remuneraci\u00f3n que le mejore su calidad de vida. Al entrar en trabajo de parto, pide un auto para ir a la cl\u00ednica y as\u00ed conoce a Selva (Est\u00e9vez), la conductora que se involucra, la acompa\u00f1a y decide no separarse de la beba. Tambi\u00e9n se hace presente en la cl\u00ednica Emma (Mariana Genesio) quien, para sorpresa de todas, ser\u00e1 parte fundamental de esta historia.<\/p>\n<p>Las cuatro mujeres trasgreden los protocolos de subrogaci\u00f3n y deciden compartir la crianza de la \u00abpeque\u00f1a Victoria\u00bb, quien las interpela y las desaf\u00eda al amor. Las mujeres encuentran un v\u00ednculo sanador que no viene dado por la maternidad sino por la relaci\u00f3n que construyen las cuatro, alrededor de la hija de todas. La llegada de Victoria traer\u00e1, adem\u00e1s, una relaci\u00f3n rom\u00e1ntica para cada una de sus madres, con personajes de Luciano Castro, Facundo Arana, Nicol\u00e1s Francella y Daniel Hendler. La idea original fue del cineasta Daniel Burman y Erika Halvorsen, pero los guionistas son Halvorsen, Mara Pescio, Ana Accorsi y Mart\u00edn Vatenberg.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un alquiler de vientre y un nacimiento unen a cuatro mujeres en Peque\u00f1a Victoria. Viacom Internacional comenz\u00f3 el rodaje de la nueva comedia dram\u00e1tica Peque\u00f1a Victoria, protagonizada por Julieta D\u00edaz, Natalie P\u00e9rez, In\u00e9s Est\u00e9vez y Mariana Genesio, y que se ver\u00e1 en el segundo semestre del a\u00f1o por Telefe. Peque\u00f1a Victoria\u00a0comienza con el nacimiento de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":65261,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[2],"tags":[24034,24035,24036],"class_list":{"0":"post-65258","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tv","8":"tag-ines-estevez-y-julieta-diaz","9":"tag-ines-estevez-y-julieta-diaz-telefe","10":"tag-pequena-victoria"},"_links":{"self":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts\/65258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/comments?post=65258"}],"version-history":[{"count":0,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts\/65258\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/media\/65261"}],"wp:attachment":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/media?parent=65258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/categories?post=65258"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/tags?post=65258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}