{"id":59099,"date":"2018-03-23T10:50:13","date_gmt":"2018-03-23T13:50:13","guid":{"rendered":"http:\/\/www.cordobatimes.com\/showup\/?p=59099"},"modified":"2020-06-20T21:08:08","modified_gmt":"2020-06-21T00:08:08","slug":"mira-el-trailer-de-the-rain-la-nueva-serie-original-de-netflix","status":"publish","type":"post","link":"https:\/\/www.cordobatimes.com\/showup\/tv\/2018\/03\/23\/mira-el-trailer-de-the-rain-la-nueva-serie-original-de-netflix\/","title":{"rendered":"Mir\u00e1 el tr\u00e1iler de The Rain la nueva serie original de Netflix"},"content":{"rendered":"<h3><strong>Es una serie danesa, original de esta plataforma por streaming, que estrenar\u00e1 pr\u00f3ximamente.<\/strong><\/h3>\n<p>El 4 de mayo estrenar\u00e1 en\u00a0Netflix\u00a0The Rain, una serie danesa original de esta plataforma por streaming.<\/p>\n<p>\u201cEl mundo como lo conocemos se ha terminado. Seis a\u00f1os despu\u00e9s, cuando un brutal virus tra\u00eddo por la lluvia hace desaparecer a casi todos los humanos en Escandinavia, dos hermanos daneses emergen desde la seguridad de su bunker para encontrar todos los restos de la civilizaci\u00f3n desaparecida. Pronto se unen a un grupo de j\u00f3venes sobrevivientes y juntos emprenden una aventura peligrosa a trav\u00e9s de una Escandinavia abandonada, en busca de cualquier se\u00f1al de vida\u201d, de esta manera se presenta la sinopsis oficial de esta producci\u00f3n.<\/p>\n<p>La ficci\u00f3n cuenta con las actuaciones estelares de Alba August. Mikkel Boe F\u00f8lsgaard, Lucas Lynggaard T\u00f8nnesen, Lars Simonsen, Iben Hjejle, Angela Bundalovic, Sonny Lindberg, Jessica Dinnage, Lukas L\u00f8kken y Johannes Kuhnke.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/3gnS_Qj-pfQ\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es una serie danesa, original de esta plataforma por streaming, que estrenar\u00e1 pr\u00f3ximamente. El 4 de mayo estrenar\u00e1 en\u00a0Netflix\u00a0The Rain, una serie danesa original de esta plataforma por streaming. \u201cEl mundo como lo conocemos se ha terminado. Seis a\u00f1os despu\u00e9s, cuando un brutal virus tra\u00eddo por la lluvia hace desaparecer a casi todos los humanos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":59100,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[2],"tags":[21353,21351],"class_list":{"0":"post-59099","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tv","8":"tag-the-rain-serie-original-de-netflix","9":"tag-trailer-de-the-rain"},"_links":{"self":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts\/59099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/comments?post=59099"}],"version-history":[{"count":0,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts\/59099\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/media\/59100"}],"wp:attachment":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/media?parent=59099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/categories?post=59099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/tags?post=59099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}