{"id":57564,"date":"2017-12-14T11:20:25","date_gmt":"2017-12-14T14:20:25","guid":{"rendered":"http:\/\/www.cordobatimes.com\/showup\/?p=57564"},"modified":"2020-06-14T08:52:33","modified_gmt":"2020-06-14T11:52:33","slug":"mira-todos-los-ganadores-los-premios-tato-2017","status":"publish","type":"post","link":"https:\/\/www.cordobatimes.com\/showup\/tv\/2017\/12\/14\/mira-todos-los-ganadores-los-premios-tato-2017\/","title":{"rendered":"Mir\u00e1 todos los ganadores de los premios Tato 2017"},"content":{"rendered":"<h3><strong>La C\u00e1mara Argentina de Productores Independientes de Televisi\u00f3n (Capit) entreg\u00f3 sus galardones a lo mejor del 2017.<\/strong><\/h3>\n<p>La miniserie Un gallo para Esculapio (Telefe\/TNT) fue distinguida como el mejor programa de 2017 en los Premios Tato otorgados por la C\u00e1mara Argentina de Productores Independientes de Televisi\u00f3n (Capit) durante una ceremonia realizada anoche en La Rural.<\/p>\n<p>La ficci\u00f3n tuvo una arrolladora performance en la noche y se impuso en once categor\u00edas: actor de reparto (Luis Luque), direcci\u00f3n de ficci\u00f3n (Bruno Stagnaro), direcci\u00f3n de arte de ficci\u00f3n (Mar\u00eda Battaglia), edici\u00f3n de ficci\u00f3n, fotograf\u00eda de ficci\u00f3n, actor protag\u00f3nico en unitario (Peter Lanzani), actriz protag\u00f3nica en unitario (Eleonora Wexler), ficci\u00f3n unitaria, gui\u00f3n original, producci\u00f3n del a\u00f1o y programa del a\u00f1o.<\/p>\n<p>M\u00e1s de 2500 miembros de la industria audiovisual estuvieron presentes en la ceremonia: entre ellos, actores, conductores y panelistas, directores, editores, guionistas, vestuaristas, anunciantes, publicistas y representantes sindicales y de las c\u00e1maras empresarias.<\/p>\n<p>En el plano period\u00edstico Telef\u00e9 tambi\u00e9n result\u00f3 la pantalla m\u00e1s premiada con Linea de tiempo (programa period\u00edstico); Rodolfo Barili y Cristina P\u00e9rez (conducci\u00f3n de noticiero); y Reynaldo Sietecase (labor period\u00edstica), que asegur\u00f3 que la misi\u00f3n del oficio \u00absigue siendo incomodar a los que tienen el poder\u00bb. El canal tambi\u00e9n se llev\u00f3 la estatuilla en el codiciado rubro \u00abNoticiero\u00bb.<\/p>\n<p>Mar\u00eda O&#8217;Donell, ganadora como conductora period\u00edstica con Ronda de editores, interpel\u00f3 la salud de la industria de medios y se\u00f1al\u00f3 que \u00abel periodismo gr\u00e1fico -el que le da forma a su programa con invitados rotativos- est\u00e1 siendo muy castigado\u00bb.<\/p>\n<p>A su vez, Marcelo Tinelli, ganador en la categor\u00eda reality y conducci\u00f3n masculina, confirm\u00f3 que en 2018 continuar\u00e1 en la pantalla de El Trece con el cl\u00e1sico ShowMatch y proyect\u00f3 para marzo o abril su retorno a la televisi\u00f3n abierta.<\/p>\n<p>Los premios, que se resolvieron seg\u00fan el criterio de un jurado integrado por 2.500 profesionales de la industria, incluyeron los ciclos de la TV abierta y de cable que se emitieron entre el 1 de noviembre del 2016 y el 31 de octubre de 2017:<\/p>\n<p>Los siguientes fueron los ganadores de la noche:<\/p>\n<p>&#8211; Programa del a\u00f1o \u00abUn gallo para Esculapio\u00bb (Telef\u00e9\/TNT).<\/p>\n<p>&#8211; Mejor Producci\u00f3n: \u00abUn gallo para Esculapio\u00bb (Telefe\/TNT).<\/p>\n<p>&#8211; Ficci\u00f3n Unitaria: \u00abUn gallo para Esculapio\u00bb (Telefe\/TNT).<\/p>\n<p>&#8211; Ficci\u00f3n Diaria Comedia: \u00abLas estrellas\u00bb (El Trece).<\/p>\n<p>&#8211; Ficci\u00f3n Diaria Drama: \u00abCu\u00e9ntame c\u00f3mo pas\u00f3\u00bb (TV P\u00fablica Argentina).<\/p>\n<p>&#8211; Ficci\u00f3n Infantil:\u00bbDivina\u00bb (El Trece).<\/p>\n<p>&#8211; Entretenimiento: \u00abPasapalabra\u00bb (El Trece).<\/p>\n<p>&#8211; Programa de Espect\u00e1culos: \u00abBendita\u00bb (El Nueve).<\/p>\n<p>&#8211; Programa de viajes: \u00abResto del mundo\u00bb (El Trece).<\/p>\n<p>&#8211; Magazine: \u00abEl diario de Mariana (El Trece).<\/p>\n<p>&#8211; Inter\u00e9s General Semanal: \u00abPh podemos hablar\u00bb (Telefe).<\/p>\n<p>&#8211; Period\u00edstico: \u00abL\u00ednea de tiempo\u00bb (Telefe).<\/p>\n<p>&#8211; Noticiero: \u00abTelefe Noticias\u00bb (Telefe).<\/p>\n<p>&#8211; Cultural: \u00abTodo tiene un por qu\u00e9\u00bb (TV P\u00fablica Argentina).<\/p>\n<p>&#8211; Reality: \u00abShowMatch\u00bb (El Trece).<\/p>\n<p>&#8211; Programa de cocina: \u00abCocineros Argentinos\u00bb (TV P\u00fablica Argentina);<\/p>\n<p>&#8211; Programa de humor: \u00abPeter Capusotto y sus videos\u00bb (El Nueve);<\/p>\n<p>&#8211; Deportivo: \u00abF\u00fatbol para todos (TV P\u00fablica Argentina).<\/p>\n<p>&#8211; Musical: \u00abEncuentro en La C\u00fapula\u00bb (TV P\u00fablica Argentina\u00bb).<\/p>\n<p>&#8211; Actriz Protag\u00f3nica Unitario: Eleonora Wexler-\u00abUn gallo para Esculapio\u00bb(Telefe\/TNT);<\/p>\n<p>&#8211; Actor Protag\u00f3nico Unitario: Peter Lanzani \u00abUn gallo para Esculapio\u00bb (Telefe\/TNT).<\/p>\n<p>&#8211; Actriz Protag\u00f3nica Diaria: Eleonora Wexler-\u00abAdda, Amar despu\u00e9s de amar\u00bb(Telefe).<\/p>\n<p>&#8211; Actor Protag\u00f3nico Diario: Luis Mach\u00edn-\u00abVida de pel\u00edcula\u00bb (TV P\u00fablica Argentina).<\/p>\n<p>&#8211; Actriz de reparto: Leonor Manso \u00abCu\u00e9ntame c\u00f3mo pas\u00f3\u00bb (TV P\u00fablica Argentina).<\/p>\n<p>&#8211; Actor de reparto: Luis Luque \u00abUn gallo para Esculapio\u00bb (Telefe\/TNT).<\/p>\n<p>&#8211; Conducci\u00f3n femenina-aire: Ver\u00f3nica Lozano-\u00abCort\u00e1 por Lozano\u00bb (Telefe).<\/p>\n<p>&#8211; Conducci\u00f3n masculina-aire: Marcelo Tinelli-\u00abShowMatch\u00bb (El Trece).<\/p>\n<p>&#8211; Conducci\u00f3n period\u00edstica: Maria O&#8217;Donnell-\u00abRonda de editores\u00bb (TV P\u00fablica Argentina).<\/p>\n<p>&#8211; Conducci\u00f3n noticiero: Rodolfo Barili y Cristina P\u00e9rez-\u00abTelefe Noticias\u00bb (Telefe).<\/p>\n<p>&#8211; Panelista: Malena Guinzburg-\u00abMorfi todos a la mesa\u00bb (Telefe).<\/p>\n<p>&#8211; Labor period\u00edstica-aire: Reynaldo Sietecase-\u00abTelefe Noticias\u00bb (Telefe).<\/p>\n<p>&#8211; Labor c\u00f3mica: Diego Capusotto-\u00abPeter Capusotto y sus videos\u00bb (El Nueve).<\/p>\n<p>&#8211; Direcci\u00f3n de ficci\u00f3n: Bruno Stagnaro-\u00abUn gallo para Esculapio\u00bb (Telefe\/TNT).<\/p>\n<p>&#8211; Gui\u00f3n original de ficci\u00f3n: Bruno Stagnaro\/Ariel Staltari-\u00abUn gallo para Esculapio\u00bb (Telefe\/TNT).<\/p>\n<p>&#8211; Direcci\u00f3n de arte en ficci\u00f3n: Mar\u00eda Battaglia-\u00abUn gallo para Esculapio\u00bb (Telefe\/TNT);<\/p>\n<p>&#8211; Vestuario en ficci\u00f3n: Ana Markarian-\u00abCu\u00e9ntame c\u00f3mo pas\u00f3\u00bb (TV P\u00fablica Argentina).<\/p>\n<p>&#8211; Direcci\u00f3n de fotograf\u00eda en ficci\u00f3n: Miguel Abal\/Gast\u00f3n Girod-\u00abUn gallo para Esculapio\u00bb (Telefe\/TNT).<\/p>\n<p>&#8211; Edici\u00f3n en ficci\u00f3n: Guillermo Gatti\/Alejandro Brodershon\/Gabriel Stagnaro\/ Fabricio Rodriguez\/Carlos Cambariere-\u00abUn gallo para Esculapio\u00bb (Telefe\/TNT).<\/p>\n<p>&#8211; Direcci\u00f3n en no ficci\u00f3n: Alejandro Ripoll-\u00abShowMatch\u00bb (El Trece).<\/p>\n<p>&#8211; Edici\u00f3n en no ficci\u00f3n: Luciano Salmi\/Agustin Rodr\u00edguez\/Julieta Denisiejko\/Facundo Chisari\/Agust\u00edn Mart\u00ednez-\u00abBendita\u00bb (El Nueve).<\/p>\n<p>&#8211; Escenograf\u00eda en no ficci\u00f3n: Gustavo Pomes-\u00abShowMatch\u00bb (El Trece).<\/p>\n<p>&#8211; Vestuario en no ficci\u00f3n: Maria Vilari\u00f1o-\u00abShowMatch\u00bb (El Trece).<\/p>\n<p>&#8211; Ficci\u00f3n corta-cable-web: \u00abLa b\u00fasqueda de Laura\u00bb (Telefe).<\/p>\n<p>&#8211; Entretenimiento\/Late Night-Cable: \u00abNet\u00bb (Fox Sports).<\/p>\n<p>&#8211; Inter\u00e9s General-Cable: \u00abEsta es mi villa\u00bb (TN).<\/p>\n<p>&#8211; Programa period\u00edstico-cable: \u00abLuis Novaresio entrevista\u00bb (A24).<\/p>\n<p>&#8211; Programa deportivo-cable: \u00abPaso a paso\u00bb (TyC Sports).<\/p>\n<p>&#8211; Programa cultural?cable: \u00abEn el camino\u00bb (TN).<\/p>\n<p>&#8211; Servicios de noticias-cable: TN.<\/p>\n<p>&#8211; Programa infantil-aire\/cable:Junior Express\u00bb (Disney Junior).<\/p>\n<p>&#8211; Conducci\u00f3n femenina-cable: Mar\u00eda O&#8217;Donnell-\u00ab50 Minutos\u00bb (LN+).<\/p>\n<p>&#8211; Conducci\u00f3n masculina-cable: Luis Novaresio-\u00abLuis Novaresio entrevista\u00bb (A24).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La C\u00e1mara Argentina de Productores Independientes de Televisi\u00f3n (Capit) entreg\u00f3 sus galardones a lo mejor del 2017. La miniserie Un gallo para Esculapio (Telefe\/TNT) fue distinguida como el mejor programa de 2017 en los Premios Tato otorgados por la C\u00e1mara Argentina de Productores Independientes de Televisi\u00f3n (Capit) durante una ceremonia realizada anoche en La Rural. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":57565,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[2],"tags":[20305],"class_list":{"0":"post-57564","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tv","8":"tag-ganadores-de-los-premios-tato-2017"},"_links":{"self":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts\/57564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/comments?post=57564"}],"version-history":[{"count":0,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts\/57564\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/media\/57565"}],"wp:attachment":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/media?parent=57564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/categories?post=57564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/tags?post=57564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}