{"id":3329,"date":"2013-11-18T23:00:44","date_gmt":"2013-11-19T02:00:44","guid":{"rendered":"http:\/\/cordobatimes.com\/showup\/?p=3329"},"modified":"2020-01-12T09:40:29","modified_gmt":"2020-01-12T12:40:29","slug":"dos-directores-cordobeses-compiten-en-el-festival-de-cine-de-mar-del-plata","status":"publish","type":"post","link":"https:\/\/www.cordobatimes.com\/showup\/cine-y-series\/2013\/11\/18\/dos-directores-cordobeses-compiten-en-el-festival-de-cine-de-mar-del-plata\/","title":{"rendered":"Dos directores cordobeses competir\u00e1n en el Festival de Cine de Mar del Plata"},"content":{"rendered":"<h3 style=\"text-align: justify;\"><strong>Luciano Juncos y Gast\u00f3n Bottaro estar\u00e1n incluidos con su realizaci\u00f3n llamada \u00abLa Laguna\u00bb en la\u00a0Competencia Oficial del 28vo. Festival de Cine de Mar del Plata\u00a0. Los gastos de la producci\u00f3n fueron solventados por todos los integrantes del proyecto.<\/strong><\/h3>\n<p style=\"text-align: justify;\">Se trata de un trabajo de tesis realizado por un grupo de 9 estudiantes, comandado por Juncos y Bottaro, y que fue filmado \u00edntegramente en las sierras de C\u00f3rdoba. El film es protagonizado por Germ\u00e1n de Silva y Gustavo Almada, y se estrenar\u00e1 ma\u00f1ana a las 14 en la sala Astor Piazzolla del Teatro Auditorium, donde volver\u00e1 a exhibirse a las 22, y el jueves pr\u00f3ximo, a las 16.30.<\/p>\n<p style=\"text-align: justify;\">\u00abLa Laguna\u00bb cuenta la historia de una b\u00fasqueda personal, en la que su protagonista, Mario, en un intento por huir de la vida urbana, se dirige hacia las sierras cordobesas para buscar una laguna que, supuestamente, tiene la propiedad de rejuvenecer el esp\u00edritu de quienes la encuentren. Pero para lograr su cometido, Mario deber\u00e1 imponerse ante los obst\u00e1culos nuevos para \u00e9l que le impondr\u00e1 la naturaleza con su geograf\u00eda r\u00fastica y desconocida, que est\u00e1 abarcada por un silencio inmenso, y donde la parquedad del hombre es la \u00fanica gu\u00eda.<\/p>\n<p style=\"text-align: justify;\">\u201cEl protagonista, a lo largo del viaje, logra comprender que \u00e9l es el \u00fanico responsable de su vida, que de \u00e9l depende estar bien o estar mal. La laguna es en definitiva el norte de esa persona y la pregunta es: \u00bfNo habr\u00e1 existido ese norte siempre en su interior?\u201d, explicaron los realizadores.<\/p>\n<p style=\"text-align: justify;\">Lo que m\u00e1s interes\u00f3 al grupo de trabajo fue que para filmar, debi\u00f3 realizar ese mismo viaje que el protagonista lleva a cabo en la ficci\u00f3n. La pel\u00edcula surgi\u00f3 a partir del proyecto que realizaron para la tesis final de la carrera de cine en la Escuela La Metro, el cual tuvo una demora de tres a\u00f1os y donde todas las personas que participaron lo hicieron totalmente <em>ad honorem<\/em> y aportando dinero de sus propio bolsillos para financiar el film.<\/p>\n<p style=\"text-align: justify;\">Respecto al envi\u00f3n disparador que los llev\u00f3 a elaborar este trabajo audiovisual, los directores aclaran que \u00abhay una intenci\u00f3n de mostrar las relaciones humanas, ese ida y vuelta, y la responsabilidad de una persona ante su vida, de estar bien o estar mal, de hacerse cargo. Hay una intenci\u00f3n de hacer \u00e9nfasis en la vuelta hacia lo natural, de mostrar el acto de viajar, el acto de compartir y de confiar. Cuestiones que concebimos como trascendentes m\u00e1s all\u00e1 de un contexto, de una \u00e9poca o lugar\u00bb.<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/sVKN1JKmQgU\" width=\"420\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p style=\"text-align: justify;\">Por Mart\u00edn Petrucci.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luciano Juncos y Gast\u00f3n Bottaro estar\u00e1n incluidos con su realizaci\u00f3n llamada \u00abLa Laguna\u00bb en la\u00a0Competencia Oficial del 28vo. Festival de Cine de Mar del Plata\u00a0. Los gastos de la producci\u00f3n fueron solventados por todos los integrantes del proyecto. Se trata de un trabajo de tesis realizado por un grupo de 9 estudiantes, comandado por Juncos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3330,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[3],"tags":[26366,28141,26367],"class_list":{"0":"post-3329","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-cine-y-series","8":"tag-directores-cordobeses-festival-de-cine-de-mar-del-plata","9":"tag-la-laguna-festival-de-cine-de-mar-del-plata","10":"tag-luciano-juncos-y-gaston-bottaro"},"_links":{"self":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts\/3329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/comments?post=3329"}],"version-history":[{"count":0,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts\/3329\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/media\/3330"}],"wp:attachment":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/media?parent=3329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/categories?post=3329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/tags?post=3329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}