{"id":102822,"date":"2024-05-12T20:05:29","date_gmt":"2024-05-12T23:05:29","guid":{"rendered":"https:\/\/www.cordobatimes.com\/showup\/?p=102822"},"modified":"2024-05-12T20:05:29","modified_gmt":"2024-05-12T23:05:29","slug":"cruce-entre-jey-mammon-y-la-periodista-valeria-sampedro-la-justicia-no-te-declaro-inocente","status":"publish","type":"post","link":"https:\/\/www.cordobatimes.com\/showup\/famosos\/2024\/05\/12\/cruce-entre-jey-mammon-y-la-periodista-valeria-sampedro-la-justicia-no-te-declaro-inocente\/","title":{"rendered":"Cruce entre Jey Mammon y la periodista Valeria Sampedro: \u201cLa Justicia no te declar\u00f3 inocente\u201d"},"content":{"rendered":"<h3><strong>El conductor protagoniz\u00f3 una acalorada discusi\u00f3n en la mesa de Juana Viale, por la causa por abuso sexual que present\u00f3 Lucas Benvenuto.<\/strong><\/h3>\n<p>Juana Viale\u00a0regres\u00f3 como conductora a\u00a0Almorzando con Juana\u00a0(El Trece), tras una larga traves\u00eda mar\u00edtima con fines ecol\u00f3gicos. En su vuelta tuvo\u00a0la presencia de\u00a0Jey Mamm\u00f3n, invitaci\u00f3n que ya ven\u00eda dando que hablar, que termin\u00f3 cruz\u00e1ndose con la periodista\u00a0Valeria Sampedro por la denuncia de Lucas Benvenuto.<\/p>\n<p>Despu\u00e9s de presentar a An\u00edbal Pachano, la doctora Mirta Verbuch y a la dupla del noticiero matutino del canal, que encabezan Valeria y Nacho Otero, la presentadora dej\u00f3 al humorista para el final, le dedic\u00f3 unas c\u00e1lidas palabras y un abrazo, quien no dud\u00f3 en llenarla de halagos por su look, un vestido rojo de terciopelo, y su nuevo corte de pelo a la altura de la mand\u00edbula.<\/p>\n<p>\u201cVengo con un futuro hermoso\u201d, se\u00f1al\u00f3 \u00e9l sobre sus proyectos en televisi\u00f3n y radio, donde expres\u00f3 que se encontraba muy feliz de aceptar su invitaci\u00f3n. Entre risas, se refiri\u00f3 a ello y Viale coment\u00f3 que \u201cella era m\u00e1s buena con las preguntas\u201d que la diva de la televisi\u00f3n. Por su parte, el humorista remat\u00f3 dici\u00e9ndole que no se diferenciaban tanto, lo que suscit\u00f3 las carcajadas de ambos.<\/p>\n<p>Pero el momento m\u00e1s fuerte del almuerzo fue cuando el artista se\u00f1al\u00f3 que pas\u00f3 momentos dif\u00edciles\u00a0tras\u00a0la denuncia por parte de Lucas Benvenuto\u00a0y\u00a0volvi\u00f3 a asegurar que la Justicia lo declar\u00f3 inocente, lo que dio pie para su encontronazo con la flamante conductora de\u00a0Arriba argentinos. \u201cYa lo habl\u00e9 un mont\u00f3n de veces, por eso miro por adelante. \u00bfQu\u00e9 pas\u00f3? Fue una relaci\u00f3n consentida que dur\u00f3 muchos a\u00f1os, nos conocimos en un boliche.\u00a0La causa que prescribi\u00f3, no porque haya pasado, porque yo\u00a0siempre sostuve que denunci\u00f3 algo que no pas\u00f3, denunci\u00f3 una edad que no era, denunci\u00f3 hechos contra su voluntad. Es decir, hechos no consentidos, por lo que hice una demanda por injurias y calumnias llevado por la cosa p\u00fablica para demostrar esa relaci\u00f3n\u201d, se explay\u00f3 ante la mirada atenta de los otros invitados, quienes fueron escuchando su versi\u00f3n sobre lo que vivi\u00f3 durante el \u00faltimo tiempo.<\/p>\n<p>\u201cEl rebote que tuvo fue que hubo una condena por parte de mucha gente.\u00a0Yo la condena social no la sent\u00ed, seguramente hay mucha gente que se qued\u00f3 reculando, pero yo creo que hay mucha gente que necesita escuchar todo ese camino\u201d, continu\u00f3 en otro momento el presentador, quien aprovech\u00f3 para explicar que no pod\u00eda ir a juicio por la verdad debido a que \u201cno era el denunciante\u201d e insisti\u00f3 con que fue, en sus propias palabras, \u201cla v\u00edctima de la situaci\u00f3n\u201d. En ese momento Sampedro intervino con contundencia. \u201cNo es inocencia, la Justicia no te declar\u00f3 inocente, lo que determina la Justicia es que la causa prescribi\u00f3. Hay una cuesti\u00f3n que excede lo que quiera pensar o creer cada uno. La causa no avanza porque la Justicia o juez entienden que pas\u00f3 mucho tiempo, el delito es viejo\u201d.<\/p>\n<p>Acto seguido, la periodista coment\u00f3 que \u201cen general, no se les cree a las v\u00edctimas, y esto es una cuesti\u00f3n hist\u00f3rica\u201d. Jey intervino: \u201cSe le cree a la falsa v\u00edctima\u201d, lanz\u00f3, filoso mientras el exanimador de La pe\u00f1a de Morfi se mostraba en desacuerdo con la presentadora del noticiero del El Trece. \u201cTendr\u00eda que haber un abogado en la mesa\u201d, se\u00f1al\u00f3, molesto.<\/p>\n<p>En otro momento del programa, el compositor coment\u00f3 que incluso su sobrino le indic\u00f3 que en el testimonio de Benvenuto \u201cno daban las cuentas\u201d, en alusi\u00f3n a que el joven se\u00f1al\u00f3 ser menor cuando comenz\u00f3 la relaci\u00f3n entre ellos. Por su parte,\u00a0Sampedro le pregunt\u00f3 c\u00f3mo pod\u00eda salir con un adolescente mientras \u00e9l estaba en sus 30, a lo cual el m\u00fasico retruc\u00f3: \u201c\u00bfNo te parece importante que \u00e9l dijo que ten\u00eda 14 a\u00f1os y lo viol\u00e9?\u201d.<\/p>\n<p>Si bien la discusi\u00f3n estuvo lejos de terminar, el exconductor de\u00a0La Pe\u00f1a de Morfi\u00a0(Telefe) aprovech\u00f3 para hablar de cu\u00e1nto le afectaron las acusaciones y explic\u00f3 que le fue bastante dif\u00edcil afrontarlas, ya que \u201clo hizo pelota\u201d e intent\u00f3 sobrellevar todo lo que se hablaba gracias al apoyo de su c\u00edrculo cercano, en especial por parte de\u00a0Alejandro Lerner. \u201cTe quer\u00e9s matar, literalmente. Yo estoy ac\u00e1 de casualidad\u201d, coment\u00f3 sobre c\u00f3mo sac\u00f3 fuerzas para seguir en pie.<\/p>\n<p>Luego del cruce que protagoniz\u00f3 con la periodista de\u00a0Arriba Argentinos\u00a0(El Trece),\u00a0el m\u00fasico se mostr\u00f3 entusiasta por su regreso a la pantalla chica. \u201cMuy feliz,\u00a0vuelvo de la mano de\u00a0Gustavo Sofovich, que vuelvo a decir que lo amo\u2026\u201d, explic\u00f3 el invitado, quien aprovech\u00f3 para sumar que le fue de mucha ayuda el apoyo de Alejandro Lerner y de Palito Ortega, a quienes no hab\u00eda nombrado en su momento pero aprovechaba para hacerlo ante las c\u00e1maras.<\/p>\n<p>Retomando el hilo, el actor coment\u00f3: \u201cVoy a estar en canal Net, de la mano de Gustavo Sofovich, vuelvo a la tele todos los d\u00edas.\u00a0Van a poder ver mi versi\u00f3n buena o mala, como dir\u00eda Lerner, que no es esta de la llorer\u00eda. Se termin\u00f3 la llorer\u00eda\u201d. Ante la consulta de c\u00f3mo iba a ser el formato, y si iba a volver su ic\u00f3nico piano, \u00e9l coment\u00f3 que todav\u00eda se encuentran en el proceso.<\/p>\n<p>Pero ese no es el \u00fanico plan que tiene para su regreso al mundo del espect\u00e1culo, sino que tambi\u00e9n estar\u00e1 en otro conocido formato. \u201cTambi\u00e9n voy a hacer radio, voy a estar en Splendid, una radio que cumple 100 a\u00f1os, de 13 a 17 horas, todos los d\u00edas\u201d, revel\u00f3.<\/p>\n<div style=\"width: 696px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-102822-1\" width=\"696\" height=\"392\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/www.cordobatimes.com\/showup\/wp-content\/uploads\/2024\/05\/rj9ecMGo-34105380.mp4?_=1\" \/><a href=\"https:\/\/www.cordobatimes.com\/showup\/wp-content\/uploads\/2024\/05\/rj9ecMGo-34105380.mp4\">https:\/\/www.cordobatimes.com\/showup\/wp-content\/uploads\/2024\/05\/rj9ecMGo-34105380.mp4<\/a><\/video><\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El conductor protagoniz\u00f3 una acalorada discusi\u00f3n en la mesa de Juana Viale, por la causa por abuso sexual que present\u00f3 Lucas Benvenuto. Juana Viale\u00a0regres\u00f3 como conductora a\u00a0Almorzando con Juana\u00a0(El Trece), tras una larga traves\u00eda mar\u00edtima con fines ecol\u00f3gicos. En su vuelta tuvo\u00a0la presencia de\u00a0Jey Mamm\u00f3n, invitaci\u00f3n que ya ven\u00eda dando que hablar, que termin\u00f3 cruz\u00e1ndose [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":102823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[4],"tags":[36643,39264,37059,39265],"class_list":{"0":"post-102822","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-famosos","8":"tag-caso-jey-mammon","9":"tag-jey-mammon-y-la-periodista-valeria-sampedro","10":"tag-jey-mammon-y-lucas-benvenuto","11":"tag-jey-mammon-y-valeria-sampedro"},"_links":{"self":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts\/102822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/comments?post=102822"}],"version-history":[{"count":0,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/posts\/102822\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/media\/102823"}],"wp:attachment":[{"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/media?parent=102822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/categories?post=102822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/showup\/wp-json\/wp\/v2\/tags?post=102822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}