{"id":29544,"date":"2015-06-20T02:58:58","date_gmt":"2015-06-20T05:58:58","guid":{"rendered":"http:\/\/www.cordobatimes.com\/deportes\/?p=29544"},"modified":"2016-08-24T19:38:54","modified_gmt":"2016-08-24T22:38:54","slug":"instituto-y-sportivo-empataron-en-san-francisco","status":"publish","type":"post","link":"https:\/\/www.cordobatimes.com\/deportes\/futbol\/2015\/06\/20\/instituto-y-sportivo-empataron-en-san-francisco\/","title":{"rendered":"Instituto y Sportivo empataron en San Francisco"},"content":{"rendered":"<h3><strong><a href=\"http:\/\/www.cordobatimes.com\/deportes\/wp-content\/uploads\/2015\/06\/ARCHI_272830.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-29545 aligncenter\" src=\"http:\/\/www.cordobatimes.com\/deportes\/wp-content\/uploads\/2015\/06\/ARCHI_272830.jpg\" alt=\"ARCHI_272830\" width=\"760\" height=\"481\" data-id=\"29545\" srcset=\"https:\/\/www.cordobatimes.com\/deportes\/wp-content\/uploads\/2015\/06\/ARCHI_272830.jpg 640w, https:\/\/www.cordobatimes.com\/deportes\/wp-content\/uploads\/2015\/06\/ARCHI_272830-300x190.jpg 300w\" sizes=\"auto, (max-width: 760px) 100vw, 760px\" \/><\/a><\/strong><\/h3>\n<h3><strong>Sportivo Belgrano de San Francisco e Instituto igualaron 0 a 0, en encuentro correspondiente a la 20\u00aa fecha del Nacional.<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p>Con este resultado, los del este cordob\u00e9s, que fueron locales en el Oscar Boero, contin\u00faan en la \u00faltima posici\u00f3n del certamen, ahora con 16 unidades, adem\u00e1s de permanecer en zona de descenso.<\/p>\n<p>Los de Alta C\u00f3rdoba suman ahora 24 puntos y acumulan cinco partidos sin conocer la derrota, producto de tres victorias y dos empates.<\/p>\n<p>El primer tiempo fue discreto, porque ninguno de los dos tuvo iniciativa para desnivelar el marcador. Pareci\u00f3 que los dos se dedicaron demasiado a analizar al rival y se mostraron muy contenidos a la hora de atacar.<\/p>\n<p>Los locales salieron decididos en el complemento y dominaron las acciones hasta los 20 minutos, aunque sin crear jugadas de real peligro hacia el arco de Lucas Hoyos.<\/p>\n<p>Pero con el correr de los minutos, el equipo de la capital provincial recuper\u00f3 protagonismo y tuvo las chances m\u00e1s claras; pero Cristian Bernardi y Gast\u00f3n Mach\u00edn definieron defectuosamente cuando hab\u00edan quedado de cara al gol, a los 27 y 30 minutos, respectivamente.<\/p>\n<p>Luego de esa r\u00e1faga de los visitantes todo volvi\u00f3 a ser muy lento y a pesar de los cambios que introdujeron Carlos Trullet, en Sportivo Belgrano, y H\u00e9ctor Rivoira, en Instituto, ninguno de los dos encontr\u00f3 v\u00edas n\u00edtidas para el gol. Por eso, el marcador no se alter\u00f3.<\/p>\n<p>El pr\u00f3ximo mi\u00e9rcoles los de San Francisco recibir\u00e1n a Ferro para recuperar el encuentro postergado de la 16\u00aa fecha.<\/p>\n<p>Instituto, en tanto, recibir\u00e1 por la pr\u00f3xima fecha a Uni\u00f3n de Mar del Plata en C\u00f3rdoba.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Sportivo Belgrano<\/strong>:<\/p>\n<p>Andr\u00e9s Bailo; Gast\u00f3n Guruceaga, C\u00e9sar Medina, Gabriel Colombatti y Agust\u00edn Garc\u00eda Basso; Alfredo Ram\u00edrez, Facundo Fabello, Gast\u00f3n \u00c1lvarez Su\u00e1rez y Nicol\u00e1s L\u00f3pez Macri; Juan Manuel Ar\u00f3stegui y Cristian Insaurralde. DT: Carlos Trullet.<\/p>\n<p><strong>Instituto<\/strong>:<\/p>\n<p>Lucas Hoyos; Jonathan Here\u00f1\u00fa, Dami\u00e1n Schmidt, Sergio Rodr\u00edguez y Leandro Sapetti; Christian Bernardi, Gast\u00f3n Mach\u00edn y Emiliano Endrizzi; Gustavo Gotti; Jonatan Bauman y Pablo Magn\u00edn. DT: H\u00e9ctor Rivoira.<\/p>\n<p>Cambio en el primer tiempo: 18m. Pablo Pavetti por Insaurralde (SB).<\/p>\n<p>Cambios en el segundo tiempo: 22m. Ignacio Antonio por Gotti (I); 26m. C\u00e9sar Carignano por Ar\u00f3stegui (SB); 35m. Leonardo Borzani por Pavetti (SB); 37m. Jos\u00e9 Luis Garc\u00eda por Endrizzi (I) y 45m. Mariano Guerreiro por Magn\u00edn (I).<\/p>\n<p>Incidencias en el segundo tiempo: \u00a045m. expulsado \u00a0S. Rodr\u00edguez (I).<\/p>\n<p>\u00c1rbitro: Pedro Arga\u00f1araz.<\/p>\n<p>Cancha: Estadio Oscar C. Boero (San Francisco)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sportivo Belgrano de San Francisco e Instituto igualaron 0 a 0, en encuentro correspondiente a la 20\u00aa fecha del Nacional. &nbsp; Con este resultado, los del este cordob\u00e9s, que fueron locales en el Oscar Boero, contin\u00faan en la \u00faltima posici\u00f3n del certamen, ahora con 16 unidades, adem\u00e1s de permanecer en zona de descenso. Los de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":29545,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[2,17],"tags":[35,123,124],"class_list":["post-29544","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-futbol","category-nacional-b","tag-instituto","tag-san-francisco","tag-sportivo-belgrano"],"_links":{"self":[{"href":"https:\/\/www.cordobatimes.com\/deportes\/wp-json\/wp\/v2\/posts\/29544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cordobatimes.com\/deportes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cordobatimes.com\/deportes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/deportes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/deportes\/wp-json\/wp\/v2\/comments?post=29544"}],"version-history":[{"count":0,"href":"https:\/\/www.cordobatimes.com\/deportes\/wp-json\/wp\/v2\/posts\/29544\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/deportes\/wp-json\/wp\/v2\/media\/29545"}],"wp:attachment":[{"href":"https:\/\/www.cordobatimes.com\/deportes\/wp-json\/wp\/v2\/media?parent=29544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/deportes\/wp-json\/wp\/v2\/categories?post=29544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/deportes\/wp-json\/wp\/v2\/tags?post=29544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}