{"id":16633,"date":"2014-07-03T13:25:25","date_gmt":"2014-07-03T16:25:25","guid":{"rendered":"http:\/\/www.cordobatimes.com\/deportes\/?p=16633"},"modified":"2014-07-03T13:26:27","modified_gmt":"2014-07-03T16:26:27","slug":"el-lobo-ledesma-seguira-su-carrera-en-argentinos-juniors","status":"publish","type":"post","link":"https:\/\/www.cordobatimes.com\/deportes\/futbol\/2014\/07\/03\/el-lobo-ledesma-seguira-su-carrera-en-argentinos-juniors\/","title":{"rendered":"El &#8220;Lobo&#8221; Ledesma seguir\u00e1 su carrera en Argentinos Juniors"},"content":{"rendered":"<h3><strong><a href=\"http:\/\/www.cordobatimes.com\/deportes\/wp-content\/uploads\/2014\/07\/Ledesma.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-16634 aligncenter\" alt=\"Ledesma\" src=\"http:\/\/www.cordobatimes.com\/deportes\/wp-content\/uploads\/2014\/07\/Ledesma.jpg\" width=\"650\" height=\"430\" data-id=\"16634\" srcset=\"https:\/\/www.cordobatimes.com\/deportes\/wp-content\/uploads\/2014\/07\/Ledesma.jpg 650w, https:\/\/www.cordobatimes.com\/deportes\/wp-content\/uploads\/2014\/07\/Ledesma-300x198.jpg 300w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><\/a><\/strong><\/h3>\n<h3 style=\"text-align: justify;\"><strong>Los Bichos de la Paternal sumaron al nuevo refuerzo, ex jugador de la casa y con mucha trayectoria, que adem\u00e1s viene de ser campe\u00f3n con River. Firm\u00f3 un contrato por un a\u00f1o y medio.<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Cristian Ledesma, el Lobo, se incorpor\u00f3 al club de sus amores y de esta manera cerrar\u00e1 su actividad profesional en el f\u00fatbol argentino. Desech\u00f3 ofertas de Primera Divisi\u00f3n, entre ellas una &#8220;suculenta&#8221; de Rosario Central. Adem\u00e1s, tras la partida de Ram\u00f3n D\u00edaz como DT del Millonario, decidi\u00f3 no continuar ligado a la instituci\u00f3n con la que gan\u00f3 el \u00faltimo campeonato de la m\u00e1xima categor\u00eda.<\/p>\n<p style=\"text-align: justify;\">El mediocampista, que tambi\u00e9n jug\u00f3 en San Lorenzo, Racing y Col\u00f3n, entre otros, tendr\u00e1 su tercer ciclo en Argentinos Juniors, donde ya visti\u00f3 la camiseta en 1997 (debut\u00f3) y luego regres\u00f3 en 2006.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los Bichos de la Paternal sumaron al nuevo refuerzo, ex jugador de la casa y con mucha trayectoria, que adem\u00e1s viene de ser campe\u00f3n con River. Firm\u00f3 un contrato por un a\u00f1o y medio. &nbsp; Cristian Ledesma, el Lobo, se incorpor\u00f3 al club de sus amores y de esta manera cerrar\u00e1 su actividad profesional en [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":16634,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[2,16],"tags":[852,3418],"class_list":["post-16633","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-futbol","category-primera-division","tag-argentinos-juniors","tag-lobo-ledesma"],"_links":{"self":[{"href":"https:\/\/www.cordobatimes.com\/deportes\/wp-json\/wp\/v2\/posts\/16633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cordobatimes.com\/deportes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cordobatimes.com\/deportes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/deportes\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/deportes\/wp-json\/wp\/v2\/comments?post=16633"}],"version-history":[{"count":0,"href":"https:\/\/www.cordobatimes.com\/deportes\/wp-json\/wp\/v2\/posts\/16633\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cordobatimes.com\/deportes\/wp-json\/wp\/v2\/media\/16634"}],"wp:attachment":[{"href":"https:\/\/www.cordobatimes.com\/deportes\/wp-json\/wp\/v2\/media?parent=16633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/deportes\/wp-json\/wp\/v2\/categories?post=16633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cordobatimes.com\/deportes\/wp-json\/wp\/v2\/tags?post=16633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}